{"id":14039,"date":"2022-04-11T15:45:53","date_gmt":"2022-04-11T14:45:53","guid":{"rendered":"https:\/\/woodpecker.co\/blog\/que-es-dkim-y-spf-y-como-configurarlo\/"},"modified":"2022-04-11T15:45:53","modified_gmt":"2022-04-11T14:45:53","slug":"que-es-dkim-y-spf-y-como-configurarlo","status":"publish","type":"post","link":"https:\/\/woodpecker.co\/blog\/es\/que-es-dkim-y-spf-y-como-configurarlo\/","title":{"rendered":"\u00bfQu\u00e9 es DKIM y SPF? \u00bfY c\u00f3mo configurarlo?"},"content":{"rendered":"<p>Esto es serio. Se trata de la entregabilidad de su correo electr\u00f3nico. S\u00e9 por experiencia propia que estos acr\u00f3nimos pueden sonar desconocidos, asustar y parecer totalmente desinteresados. O tal vez le suenen, pero nunca se preocup\u00f3 lo suficiente como para comprobar lo que realmente son.<\/p>\n<p>En cualquier caso, es hora de aprender un poco sobre qu\u00e9 es SPF y DKIM y c\u00f3mo configurarlos <a href=\"https:\/\/woodpecker.co\/blog\/what-is-dns\/\">en los registros DNS<\/a> de tu servidor de correo, si quieres tener un mejor control sobre la entregabilidad de tu correo electr\u00f3nico. Tambi\u00e9n te mostrar\u00e9 d\u00f3nde puedes comprobar en Woodpecker si est\u00e1n configurados correctamente.<\/p>\n<p>Har\u00e9 todo lo posible para explicarlo con palabras sencillas, que ser\u00e1n entendidas no s\u00f3lo por los programadores.<\/p>\n<h2>\u00bfQu\u00e9 es el SPF? \u00bfC\u00f3mo funciona el SPF?<\/h2>\n<p>En pocas palabras, Sender Policy Framework (SPF) es un mecanismo de seguridad creado para evitar que los malos env\u00eden correos electr\u00f3nicos en su nombre. El mecanismo tiene que ver con la comunicaci\u00f3n entre servidores DNS&#8230; \u00a1y aqu\u00ed es donde todo empieza a dar miedo! Pero que no cunda el p\u00e1nico. Intentar\u00e9 hacerlo lo m\u00e1s sencillo posible.<\/p>\n<p>Digamos que has enviado un correo electr\u00f3nico a Bob. Pero, \u00bfc\u00f3mo sabe el servidor DNS de Bob que el correo electr\u00f3nico ha sido enviado por ti? El problema es que no lo sabe. A no ser que tengas configurado el SPF en tu servidor DNS.<\/p>\n<p>El SPF define qu\u00e9 direcciones IP pueden utilizarse para enviar correos electr\u00f3nicos desde tu dominio. As\u00ed que imaginemos dos posibles &#8220;conversaciones&#8221; de servidor. Para hacerlo todo m\u00e1s f\u00e1cil, vamos a suponer que tu nombre es Mike.<\/p>\n<h3>Escenario 1 &#8211; No tienes configurado el SPF.<\/h3>\n<p><strong>El servidor de Mike<\/strong>: <em>Hola, servidor de Bob. Tengo un nuevo mensaje de Mike.<\/em><br \/>\n<strong>Servidor de Bob:<\/strong><em> Hola servidor de Mike. \u00bfCu\u00e1l es tu SPF?<\/em><br \/>\n<strong>Servidor de Mike<\/strong>: <em>S\u00ed, sobre el SPF&#8230; A qui\u00e9n le importa, en realidad. No tengo ninguno. Conf\u00eda en m\u00ed, es de Mike.<\/em><br \/>\n<strong>Servidor de Bob:<\/strong> <em>Si no tienes SPF, no puedo estar seguro de que fue Mike quien envi\u00f3 esto. Dame las IPs permitidas de Mike, para que pueda compararlas con las tuyas.<\/em><br \/>\n<strong>Servidor de Mike<\/strong>: <em>No tengo la lista de IPs permitidas de Mike.<\/em><br \/>\n<strong>Servidor de Bob:<\/strong> <em>Entonces no quiero tu mensaje. Entrega denegada. Lo siento, amigo&#8230;<\/em><\/p>\n<h3>Escenario 2 &#8211; S\u00ed tienes configurado el SPF.<\/h3>\n<p><strong>Servidor de Mike<\/strong>: <em>Hola, servidor de Bob. Tengo un nuevo mensaje de Mike.<\/em><br \/>\n<strong>Servidor de Bob<\/strong>:<em> Hola servidor de Mike. \u00bfCu\u00e1l es tu SPF?<\/em><br \/>\n<strong>Servidor de Mike<\/strong>:<em> Ah\u00ed tienes, aqu\u00ed est\u00e1 mi SPF. Hay toda una lista de IPs que el propio Mike declar\u00f3 como las que se pueden utilizar en su nombre.<\/em><br \/>\n<strong>Servidor de Bob:<\/strong><em> Ok, d\u00e9jame ver&#8230; Y el mensaje que tienes para mi es enviado desde la IP 64.233.160.19. Ok, est\u00e1 en la lista. Todo parece estar bien. Dame el mensaje, se lo mostrar\u00e9 a Bob. Gracias.<\/em><\/p>\n<p>Mis disculpas a todos los lectores expertos en tecnolog\u00eda de este blog por esta ignorante simplificaci\u00f3n. Por favor, perdonadnos a los tontos, y tened en cuenta que os envidiamos vuestras mentes superanal\u00edticas.<\/p>\n<p>En cualquier caso, la moraleja de estos dos breves di\u00e1logos es: configure su FPS. Si no lo haces, puedes parecer un mal tipo, y no todos tus correos electr\u00f3nicos ser\u00e1n entregados.<br \/>\n\n<aside class=\"cta-block cta-block--a-version js-cta-block ab-no-10-cta-block ab-no-11-cta-block\">\n  <p class=\"cta-block__heading u-heading-preset-md-600\">More emails<br \/>\nto the main inbox<\/p>\n  <div class=\"cta-block__form-container\">\n    <form class=\"js-cta-block-form\" action=\"https:\/\/woodpecker.co\/signup\/\" class=\"cta-block__button-only-form js-cta-block-no-input-form\">\n      \n\n\n\n\n\n\n\n\n<button class=\"c-button js-button c-button--color-main c-button--size-small u-focus-visible-outline\">\nIniciar prueba gratuita\n<\/button>    <\/form>\n    \n    <form class=\"c-input-button-form js-cta-block-form cta-block__form\" action=\"https:\/\/woodpecker.co\/signup\/\" method=\"POST\" novalidate>\n        \n  <div class=\"c-form-field js-form-field  c-input-button-form__form-field\">\n    \n    <label class=\"c-label c-form-field__label\" for=\"cta-block-form-email-311953126\">Work email<\/label>\n\n                    \n  <input class=\"c-input  js-input c-input-button-form__input\" placeholder=\"will@woodpecker.co\" name=\"email\" id=\"cta-block-form-email-311953126\" type=\"email\" \/>\n            \n    <span class=\"c-form-field__error js-error\">\n                                      Invalid email format\n        \n\n                <\/span>\n  <\/div>\n\n        <div class=\"c-input-button-form__button\">\n          \n\n\n\n\n\n\n\n\n<button class=\"cta-block__button c-button js-button c-button--color-main c-button--size-small u-focus-visible-outline\">\n                Iniciar prueba gratuita\n        \n\n<\/button>        <\/div>\n\n            <\/form>\n  <\/div>\n<\/aside><\/p>\n<h2>\u00bfQu\u00e9 aplicaciones debe incluir en su SPF?<\/h2>\n<p>La idea general es asegurarse de que todas las aplicaciones que env\u00edan correos electr\u00f3nicos en su nombre (y que utilizan su propio SMTP, no el suyo) est\u00e1n incluidas en su SPF. Por ejemplo, si utilizas Google Apps para enviar correos electr\u00f3nicos desde tu dominio, debes incluir a Google en tu SPF. Aqu\u00ed tienes<a href=\"https:\/\/support.google.com\/a\/answer\/33786?hl=en&amp;visit_id=637825833060713579-1150334745&amp;rd=1\"> las instrucciones de Google<\/a> sobre c\u00f3mo hacerlo.<\/p>\n<p>Pero es importante asegurarse, si Google es la \u00fanica aplicaci\u00f3n que debes &#8220;permitir&#8221; en tu SPF. Por ejemplo, utilizamos HelpScout para gestionar nuestros correos electr\u00f3nicos de asistencia y MailChimp para enviar nuestros boletines. Incluimos ambas en nuestro SPF.<\/p>\n<h3>\u00bfDeber\u00eda incluir tambi\u00e9n a Woodpecker en mi SPF?<\/h3>\n<p>No. Como he mencionado, debes recordar poner en tu registro SPF las aplicaciones que env\u00edan correos electr\u00f3nicos en tu nombre, pero que utilizan su propio SMTP. Woodpecker utiliza su SMTP para enviar sus correos electr\u00f3nicos, por lo que es m\u00e1s un cliente de correo electr\u00f3nico en l\u00ednea con superpoderes que una aplicaci\u00f3n de env\u00edo masivo de correos electr\u00f3nicos.<\/p>\n<p>Dicho esto, la entregabilidad de los correos electr\u00f3nicos enviados desde Woodpecker depende de la reputaci\u00f3n de tu dominio. Configurar el SPF y el DKIM te ayudar\u00e1 a proteger la buena reputaci\u00f3n de tu dominio y, por tanto, a mejorar la entregabilidad de tus correos electr\u00f3nicos.<\/p>\n<h2>\u00bfC\u00f3mo configurar el registro SPF en su servidor paso a paso?<\/h2>\n<p>El primer paso es comprobar cu\u00e1l es su registro SPF actual. Puede hacerlo utilizando herramientas como<\/p>\n<p><a href=\"https:\/\/mxtoolbox.com\/SuperTool.aspx\">MxToolbox<\/a><\/p>\n<p><a href=\"https:\/\/toolbox.googleapps.com\/apps\/checkmx\/\">Google Apps Toolbox<\/a><\/p>\n<p>Cuando escribas tu dominio all\u00ed (por ejemplo, yo escribir\u00eda woodpecker.co), las herramientas realizar\u00e1n algunas pruebas y te mostrar\u00e1n tu SPF actual, o una notificaci\u00f3n de que a\u00fan no se ha configurado.<\/p>\n<h3>\u00bfCu\u00e1les son los siguientes pasos?<\/h3>\n<p>Dependiendo del host de tu dominio, los pasos ser\u00e1n diferentes. B\u00e1sicamente, se trata de pegar una l\u00ednea de texto correctamente estructurada en el lugar adecuado de la consola.<\/p>\n<p>Por ejemplo, si utilizas Google Apps para enviar todos los correos electr\u00f3nicos desde tu dominio, la l\u00ednea tendr\u00eda el siguiente aspecto<\/p>\n<p><strong>&#8220;v=spf1 include:_spf.google.com ~all&#8221;<\/strong><\/p>\n<p>The &#8220;<strong>v=spf1<\/strong>&#8221;<\/p>\n<p>del registro se llama versi\u00f3n, y las que vienen despu\u00e9s se llaman mecanismos.<\/p>\n<p>Veamos ahora qu\u00e9 significa exactamente cada parte.<\/p>\n<ol>\n<li><strong>v=spf1<\/strong> este elemento identifica el registro como un SPF<\/li>\n<li><strong>include:_spf.google.com<\/strong> este mecanismo incluye los servidores de correo que est\u00e1n autorizados<\/li>\n<li><strong>~este indica<\/strong> que si se recibe un correo electr\u00f3nico de un servidor no autorizado (no incluido en el mecanismo &#8220;include:&#8221;), se etiqueta como fallo suave, lo que significa que se puede dejar pasar, pero podr\u00eda marcarse como spam o sospechoso.<\/li>\n<\/ol>\n<p>Pero si utilizas m\u00e1s aplicaciones (por ejemplo, algo para enviar tu bolet\u00edn de noticias, algo para enviar tus mensajes de soporte, etc.), la l\u00ednea ser\u00e1 un poco m\u00e1s larga, porque tendr\u00e1s que incluir todas las dem\u00e1s aplicaciones en ella. O si no utilizas Google Apps sino un servidor de otro host, por ejemplo, GoDaddy, la l\u00ednea tendr\u00e1 un aspecto diferente.<\/p>\n<p>A continuaci\u00f3n te explicamos c\u00f3mo configurar el SPF para los hosts de dominio m\u00e1s comunes:<\/p>\n<ul>\n<li><a href=\"https:\/\/support.google.com\/a\/answer\/33786?hl=en\">Google<\/a><\/li>\n<li><a href=\"https:\/\/docs.microsoft.com\/pl-pl\/microsoft-365\/security\/office-365-security\/set-up-spf-in-office-365-to-help-prevent-spoofing?view=o365-worldwide\">Microsoft<\/a><\/li>\n<li><a href=\"https:\/\/www.zoho.com\/mail\/help\/adminconsole\/spf-configuration.html\">Zoho<\/a><\/li>\n<li><a href=\"https:\/\/www.namecheap.com\/support\/knowledgebase\/article.aspx\/317\/2237\/how-do-i-add-txtspfdkimdmarc-records-for-my-domain\/\">NameCheap<\/a><\/li>\n<li><a href=\"https:\/\/pl.godaddy.com\/help\/add-an-spf-record-19218\">GoDaddy<\/a><\/li>\n<li><a href=\"https:\/\/docs.aws.amazon.com\/ses\/latest\/dg\/Welcome.html\">Amazon SES<\/a><\/li>\n<\/ul>\n<p>O puedes ver esta gu\u00eda paso a paso en la que nuestra Jefa de Soporte, Julia, explica c\u00f3mo hacerlo:<\/p>\n<p><center><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/v09qFY5Nakk\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/center><br \/>\nSi est\u00e1s usando o probando <a href=\"https:\/\/woodpecker.co\/\">Woodpecker<\/a> y no est\u00e1s seguro de si tu SPF est\u00e1 bien configurado, puedes comprobarlo directamente en la aplicaci\u00f3n: ve a CONFIGURACI\u00d3N &gt; CUENTAS DE CORREO &gt; ENTREGABILIDAD (en el lado izquierdo) o ponte en contacto con nosotros en <a href=\"mailto:support@woodpecker.co\">support@woodpecker<\/a>.co para obtener ayuda individual.<br \/>\n\n<aside class=\"cta-block cta-block--a-version js-cta-block ab-no-10-cta-block ab-no-11-cta-block\">\n  <p class=\"cta-block__heading u-heading-preset-md-600\">Start improving deliverability for free<\/p>\n  <div class=\"cta-block__form-container\">\n    <form class=\"js-cta-block-form\" action=\"https:\/\/woodpecker.co\/signup\/\" class=\"cta-block__button-only-form js-cta-block-no-input-form\">\n      \n\n\n\n\n\n\n\n\n<button class=\"c-button js-button c-button--color-main c-button--size-small u-focus-visible-outline\">\nIniciar prueba gratuita\n<\/button>    <\/form>\n    \n    <form class=\"c-input-button-form js-cta-block-form cta-block__form\" action=\"https:\/\/woodpecker.co\/signup\/\" method=\"POST\" novalidate>\n        \n  <div class=\"c-form-field js-form-field  c-input-button-form__form-field\">\n    \n    <label class=\"c-label c-form-field__label\" for=\"cta-block-form-email-919164259\">Work email<\/label>\n\n                    \n  <input class=\"c-input  js-input c-input-button-form__input\" placeholder=\"will@woodpecker.co\" name=\"email\" id=\"cta-block-form-email-919164259\" type=\"email\" \/>\n            \n    <span class=\"c-form-field__error js-error\">\n                                      Invalid email format\n        \n\n                <\/span>\n  <\/div>\n\n        <div class=\"c-input-button-form__button\">\n          \n\n\n\n\n\n\n\n\n<button class=\"cta-block__button c-button js-button c-button--color-main c-button--size-small u-focus-visible-outline\">\n                Iniciar prueba gratuita\n        \n\n<\/button>        <\/div>\n\n            <\/form>\n  <\/div>\n<\/aside><\/p>\n<h2>\u00bfQu\u00e9 es DKIM?<\/h2>\n<p>El est\u00e1ndar DomainKeys Identified Mail (DKIM) se ha creado por la misma raz\u00f3n que el SPF: para evitar que los malos se hagan pasar por un remitente de correo electr\u00f3nico. Es una forma de firmar adicionalmente sus correos electr\u00f3nicos de manera que el servidor del destinatario pueda comprobar si el remitente era realmente usted o no.<\/p>\n<p>Al configurar DKIM en tu servidor DNS, est\u00e1s a\u00f1adiendo una forma adicional de decir a tus receptores &#8220;s\u00ed, soy yo quien env\u00eda este mensaje&#8221;.<\/p>\n<img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-14043\" src=\"https:\/\/woodpecker.co\/blog\/app\/uploads\/2020\/12\/dkim_i_spf-01-1.png\" alt=\"how to set up dkim and spf\" width=\"700\" height=\"465\" srcset=\"https:\/\/woodpecker.co\/blog\/app\/uploads\/2020\/12\/dkim_i_spf-01-1.png 700w, https:\/\/woodpecker.co\/blog\/app\/uploads\/2020\/12\/dkim_i_spf-01-1-300x199.png 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/>\n<p>La idea se basa en cifrar y descifrar la firma adicional, puesta en la <a href=\"https:\/\/support.google.com\/mail\/answer\/29436?hl=en&amp;visit_id=637825833060713579-1150334745&amp;rd=1\">cabecera<\/a> de su mensaje. Para que eso sea posible, necesitas tener dos claves<\/p>\n<ul>\n<li><strong>la clave privada<\/strong> (que es \u00fanica para tu dominio y est\u00e1 disponible exclusivamente para ti. Te permite cifrar tu firma en el encabezado de tus mensajes).<\/li>\n<li><strong>la clave p\u00fablica<\/strong> (que a\u00f1ades a tus registros DNS utilizando el est\u00e1ndar DKIM, para permitir que el servidor de tu destinatario la recupere y descifre tu firma oculta en la cabecera de tu mensaje).<\/li>\n<\/ul>\n<img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/static-ssl.businessinsider.com\/image\/574c75aedd0895d2438b46e7-960-720\/sansa-is-writing-letters-with-the-stark-seal-this-episode-will-really-be-a-focal-point-of-the-starks-vengeance.jpg\" alt=\"Image result for direwolf seal\" \/>\n<p>F\u00edjese en Juego de Tronos para entender mejor el concepto de DKIM. Ned Stark env\u00eda un cuervo con un mensaje al rey Robert. Cualquiera podr\u00eda coger un papel, escribir un mensaje y firmarlo Ned Stark. Pero hay una forma de autentificar el mensaje: el sello. Ahora, todos saben que el sello de Ned es un lobo huargo (esa es la clave p\u00fablica). Pero s\u00f3lo Ned tiene el sello original y puede ponerlo en sus mensajes (esa es la clave privada).<\/p>\n<p>Establecer DKIM es s\u00f3lo poner la informaci\u00f3n sobre la clave p\u00fablica en los registros de su servidor. Tambi\u00e9n es un registro txt que hay que poner en el lugar correcto.<\/p>\n<p>Una vez que lo hayas configurado, cada vez que alguien reciba un correo tuyo, el servidor del receptor intentar\u00e1 descifrar tu firma oculta utilizando la clave p\u00fablica. Si tiene \u00e9xito, esto autenticar\u00e1 adicionalmente su mensaje y, en consecuencia, aumentar\u00e1 la capacidad de entrega de todos sus correos electr\u00f3nicos.<\/p>\n<h2>\u00bfC\u00f3mo configurar el registro DKIM en su servidor paso a paso?<\/h2>\n<p>En primer lugar, debe generar la clave p\u00fablica. Para ello, debe acceder a la consola de administraci\u00f3n de su proveedor de correo electr\u00f3nico. Los siguientes pasos pueden ser diferentes dependiendo de tu proveedor de correo electr\u00f3nico.<\/p>\n<p>Si utilizas Google Apps para enviar tus correos electr\u00f3nicos, aqu\u00ed tienes <a href=\"https:\/\/support.google.com\/a\/answer\/174124?hl=en\">las instrucciones<\/a> paso a paso. Los usuarios de correo electr\u00f3nico de Google Apps deben saber que, por defecto, las firmas DKIM est\u00e1n desactivadas, por lo que deben activarlas manualmente en su consola de administraci\u00f3n de Google.<\/p>\n<p>Cuando tengas la clave p\u00fablica, coge el registro txt generado y p\u00e9galo en el lugar adecuado en tus registros DNS.<\/p>\n<img decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-14044 size-full\" src=\"https:\/\/woodpecker.co\/blog\/app\/uploads\/2016\/09\/domain-dkim-add.png\" alt=\"how to add dkim to a domain\" width=\"516\" height=\"387\" srcset=\"https:\/\/woodpecker.co\/blog\/app\/uploads\/2016\/09\/domain-dkim-add.png 516w, https:\/\/woodpecker.co\/blog\/app\/uploads\/2016\/09\/domain-dkim-add-300x225.png 300w\" sizes=\"(max-width: 516px) 100vw, 516px\" \/>\n<p>Por \u00faltimo, tienes que activar la firma de correo electr\u00f3nico para empezar a enviar correos electr\u00f3nicos que incluyan tu firma cifrada con tu clave privada. Si utilizas Google Apps para enviar tus correos electr\u00f3nicos, te explicamos<a href=\"https:\/\/support.google.com\/a\/answer\/180504\"> c\u00f3mo hacerlo.<\/a><\/p>\n<p>A continuaci\u00f3n, te explicamos c\u00f3mo configurar DKIM en algunos de los otros hosts de dominio:<\/p>\n<ul>\n<li><a href=\"https:\/\/docs.microsoft.com\/pl-pl\/microsoft-365\/security\/office-365-security\/use-dkim-to-validate-outbound-email?view=o365-worldwide\">Microsoft<\/a><\/li>\n<li><a href=\"https:\/\/www.zoho.com\/mail\/help\/adminconsole\/dkim-configuration.html\">Zoho<\/a><\/li>\n<li><a href=\"https:\/\/www.namecheap.com\/support\/knowledgebase\/article.aspx\/317\/2237\/how-do-i-add-txtspfdkimdmarc-records-for-my-domain\/\">NameCheap<\/a><\/li>\n<\/ul>\n<p>Para m\u00e1s detalles, mira una gu\u00eda en v\u00eddeo que explica c\u00f3mo hacerlo:<\/p>\n<p><center><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/DMc0WkzWcFY\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/center>&nbsp;<\/p>\n<p>Si actualmente usas <a href=\"https:\/\/woodpecker.co\/\">Woodpecker<\/a> y no tienes una persona de TI a la que pedir ayuda con la configuraci\u00f3n de SPF y DKIM, puedes contactar con nosotros en support@woodpecker.co para obtener ayuda individual.<\/p>\n<p>Si quieres comprobar si tus SPF y DKIM est\u00e1n bien configurados, puedes hacerlo en la aplicaci\u00f3n: ve a CONFIGURACI\u00d3N &gt; CUENTAS DE CORREO &gt; ENTREGA (en el lado izquierdo).<\/p>\n<h2>Configure el SPF y el DKIM y mejore su capacidad de entrega<\/h2>\n<p>Si env\u00edas muchos correos electr\u00f3nicos, ya sea para marketing o para ventas entrantes o salientes, la reputaci\u00f3n de tu dominio es crucial y debes cuidarla muy bien. No quieres que tu dominio entre en una lista negra y que tus correos electr\u00f3nicos acaben en el spam. Configurar correctamente los registros SPF y DKIM en tu servidor DNS es un paso necesario para la seguridad de tu dominio y la alta entregabilidad de tus mensajes.<\/p>\n<p>Configurarlo puede parecer complicado, pero sin duda merece la pena el esfuerzo. Si yo fuera t\u00fa, ir\u00eda a mi cuenta de Woodpecker y comprobar\u00eda si mi SPF y DKIM est\u00e1n bien configurados ahora mismo o pedir\u00eda a mis inform\u00e1ticos que lo hicieran (si no eres usuario de Woodpecker). Y si resulta que la respuesta es &#8220;no&#8221;, les pedir\u00eda que me ayudaran. Y no dejar\u00eda que me dieran largas. No con esto.<\/p>\n<p>Consulta tambi\u00e9n estos cuatro posts sobre la entregabilidad del correo electr\u00f3nico:<\/p>\n<ul>\n<li><a href=\"https:\/\/woodpecker.co\/blog\/boost-cold-email-deliverability\/\">\u00bfQu\u00e9 podemos hacer para aumentar la capacidad de entrega de nuestro correo electr\u00f3nico en fr\u00edo? &gt;&gt;<\/a><\/li>\n<li><a href=\"https:\/\/woodpecker.co\/blog\/mailbox-for-outbound\/\">\u00bfPor qu\u00e9 debemos crear un buz\u00f3n independiente para las campa\u00f1as salientes? &gt;&gt;<\/a><\/li>\n<li><a href=\"https:\/\/woodpecker.co\/blog\/deliverability-faq\/\">Respuestas a 8 preguntas frecuentes sobre la entregabilidad del correo electr\u00f3nico &gt;&gt;<\/a><\/li>\n<li><a href=\"https:\/\/woodpecker.co\/blog\/deliverability-checks\/\">14 comprobaciones de entregabilidad que debe realizar antes de enviar su campa\u00f1a de correo electr\u00f3nico en fr\u00edo &gt;&gt;<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Esto es serio. Se trata de la entregabilidad de su correo electr\u00f3nico. S\u00e9 por experiencia propia que estos acr\u00f3nimos pueden sonar desconocidos, asustar y parecer totalmente desinteresados. O tal vez le suenen, pero nunca se preocup\u00f3 lo suficiente como para comprobar lo que realmente son.<\/p>\n","protected":false},"author":2,"featured_media":14041,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[60],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>SPF y DKIM para tontos: \u00bfQu\u00e9 es? Por qu\u00e9 conviene configurarlo<\/title>\n<meta name=\"description\" content=\"Gu\u00eda de SPF y DKIM para dummies. Aprenda qu\u00e9 son y c\u00f3mo configurarlos en sus registros DNS, para un mejor control de la entregabilidad de su correo electr\u00f3nico.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/woodpecker.co\/blog\/es\/que-es-dkim-y-spf-y-como-configurarlo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SPF y DKIM para tontos: \u00bfQu\u00e9 es? Por qu\u00e9 conviene configurarlo\" \/>\n<meta property=\"og:description\" content=\"Gu\u00eda de SPF y DKIM para dummies. Aprenda qu\u00e9 son y c\u00f3mo configurarlos en sus registros DNS, para un mejor control de la entregabilidad de su correo electr\u00f3nico.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/woodpecker.co\/blog\/es\/que-es-dkim-y-spf-y-como-configurarlo\/\" \/>\n<meta property=\"og:site_name\" content=\"Woodpecker Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/business.facebook.com\/woodpeckerapp\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-11T14:45:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/woodpecker.co\/blog\/app\/uploads\/2020\/07\/What_is_DKIM__SPF_And_How_to_Set_It_Up__2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"650\" \/>\n\t<meta property=\"og:image:height\" content=\"391\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Cathy Dawiskiba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/kapatalas\" \/>\n<meta name=\"twitter:site\" content=\"@woodpeckerapp\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/woodpecker.co\/blog\/es\/que-es-dkim-y-spf-y-como-configurarlo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/woodpecker.co\/blog\/es\/que-es-dkim-y-spf-y-como-configurarlo\/\"},\"author\":{\"name\":\"Cathy Dawiskiba\",\"@id\":\"https:\/\/woodpecker.co\/blog\/#\/schema\/person\/ef0d7f439f5185f3655b45d8ad3462fd\"},\"headline\":\"\u00bfQu\u00e9 es DKIM y SPF? \u00bfY c\u00f3mo configurarlo?\",\"datePublished\":\"2022-04-11T14:45:53+00:00\",\"dateModified\":\"2022-04-11T14:45:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/woodpecker.co\/blog\/es\/que-es-dkim-y-spf-y-como-configurarlo\/\"},\"wordCount\":2095,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/woodpecker.co\/blog\/#organization\"},\"articleSection\":[\"Deliverability\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/woodpecker.co\/blog\/es\/que-es-dkim-y-spf-y-como-configurarlo\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/woodpecker.co\/blog\/es\/que-es-dkim-y-spf-y-como-configurarlo\/\",\"url\":\"https:\/\/woodpecker.co\/blog\/es\/que-es-dkim-y-spf-y-como-configurarlo\/\",\"name\":\"SPF y DKIM para tontos: \u00bfQu\u00e9 es? Por qu\u00e9 conviene configurarlo\",\"isPartOf\":{\"@id\":\"https:\/\/woodpecker.co\/blog\/#website\"},\"datePublished\":\"2022-04-11T14:45:53+00:00\",\"dateModified\":\"2022-04-11T14:45:53+00:00\",\"description\":\"Gu\u00eda de SPF y DKIM para dummies. Aprenda qu\u00e9 son y c\u00f3mo configurarlos en sus registros DNS, para un mejor control de la entregabilidad de su correo electr\u00f3nico.\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/woodpecker.co\/blog\/es\/que-es-dkim-y-spf-y-como-configurarlo\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/woodpecker.co\/blog\/#website\",\"url\":\"https:\/\/woodpecker.co\/blog\/\",\"name\":\"Woodpecker Blog\",\"description\":\"Woodpecker Blog - Pro Tips on Cold Emails, Follow-ups, Sales &amp; Growth\",\"publisher\":{\"@id\":\"https:\/\/woodpecker.co\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/woodpecker.co\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/woodpecker.co\/blog\/#organization\",\"name\":\"Woodpecker.co\",\"url\":\"https:\/\/woodpecker.co\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/woodpecker.co\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/woodpecker.co\/blog\/app\/uploads\/2015\/06\/WP_Logo_WersjaPodstawowa_Pionowa_CzarneTlo_RGB.jpg\",\"contentUrl\":\"https:\/\/woodpecker.co\/blog\/app\/uploads\/2015\/06\/WP_Logo_WersjaPodstawowa_Pionowa_CzarneTlo_RGB.jpg\",\"width\":1240,\"height\":874,\"caption\":\"Woodpecker.co\"},\"image\":{\"@id\":\"https:\/\/woodpecker.co\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/business.facebook.com\/woodpeckerapp\",\"https:\/\/twitter.com\/woodpeckerapp\",\"https:\/\/www.instagram.com\/woodpeckerapp\/\",\"https:\/\/www.linkedin.com\/company\/woodpecker-co\/\",\"https:\/\/www.youtube.com\/channel\/UCNN9wM55yaNI-KEZCfh66_A\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/woodpecker.co\/blog\/#\/schema\/person\/ef0d7f439f5185f3655b45d8ad3462fd\",\"name\":\"Cathy Dawiskiba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/woodpecker.co\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5c879fd5792a7f64321f42046c8789dc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5c879fd5792a7f64321f42046c8789dc?s=96&d=mm&r=g\",\"caption\":\"Cathy Dawiskiba\"},\"description\":\"Cathy started this blog a long time ago, though it seems like it was yesterday.\",\"sameAs\":[\"https:\/\/linkedin.com\/in\/kapatalas\",\"https:\/\/twitter.com\/https:\/\/twitter.com\/kapatalas\"],\"url\":\"https:\/\/woodpecker.co\/blog\/es\/author\/cathy\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SPF y DKIM para tontos: \u00bfQu\u00e9 es? Por qu\u00e9 conviene configurarlo","description":"Gu\u00eda de SPF y DKIM para dummies. Aprenda qu\u00e9 son y c\u00f3mo configurarlos en sus registros DNS, para un mejor control de la entregabilidad de su correo electr\u00f3nico.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/woodpecker.co\/blog\/es\/que-es-dkim-y-spf-y-como-configurarlo\/","og_locale":"es_ES","og_type":"article","og_title":"SPF y DKIM para tontos: \u00bfQu\u00e9 es? Por qu\u00e9 conviene configurarlo","og_description":"Gu\u00eda de SPF y DKIM para dummies. Aprenda qu\u00e9 son y c\u00f3mo configurarlos en sus registros DNS, para un mejor control de la entregabilidad de su correo electr\u00f3nico.","og_url":"https:\/\/woodpecker.co\/blog\/es\/que-es-dkim-y-spf-y-como-configurarlo\/","og_site_name":"Woodpecker Blog","article_publisher":"https:\/\/business.facebook.com\/woodpeckerapp","article_published_time":"2022-04-11T14:45:53+00:00","og_image":[{"width":650,"height":391,"url":"https:\/\/woodpecker.co\/blog\/app\/uploads\/2020\/07\/What_is_DKIM__SPF_And_How_to_Set_It_Up__2.png","type":"image\/png"}],"author":"Cathy Dawiskiba","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/kapatalas","twitter_site":"@woodpeckerapp","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/woodpecker.co\/blog\/es\/que-es-dkim-y-spf-y-como-configurarlo\/#article","isPartOf":{"@id":"https:\/\/woodpecker.co\/blog\/es\/que-es-dkim-y-spf-y-como-configurarlo\/"},"author":{"name":"Cathy Dawiskiba","@id":"https:\/\/woodpecker.co\/blog\/#\/schema\/person\/ef0d7f439f5185f3655b45d8ad3462fd"},"headline":"\u00bfQu\u00e9 es DKIM y SPF? \u00bfY c\u00f3mo configurarlo?","datePublished":"2022-04-11T14:45:53+00:00","dateModified":"2022-04-11T14:45:53+00:00","mainEntityOfPage":{"@id":"https:\/\/woodpecker.co\/blog\/es\/que-es-dkim-y-spf-y-como-configurarlo\/"},"wordCount":2095,"commentCount":0,"publisher":{"@id":"https:\/\/woodpecker.co\/blog\/#organization"},"articleSection":["Deliverability"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/woodpecker.co\/blog\/es\/que-es-dkim-y-spf-y-como-configurarlo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/woodpecker.co\/blog\/es\/que-es-dkim-y-spf-y-como-configurarlo\/","url":"https:\/\/woodpecker.co\/blog\/es\/que-es-dkim-y-spf-y-como-configurarlo\/","name":"SPF y DKIM para tontos: \u00bfQu\u00e9 es? Por qu\u00e9 conviene configurarlo","isPartOf":{"@id":"https:\/\/woodpecker.co\/blog\/#website"},"datePublished":"2022-04-11T14:45:53+00:00","dateModified":"2022-04-11T14:45:53+00:00","description":"Gu\u00eda de SPF y DKIM para dummies. Aprenda qu\u00e9 son y c\u00f3mo configurarlos en sus registros DNS, para un mejor control de la entregabilidad de su correo electr\u00f3nico.","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/woodpecker.co\/blog\/es\/que-es-dkim-y-spf-y-como-configurarlo\/"]}]},{"@type":"WebSite","@id":"https:\/\/woodpecker.co\/blog\/#website","url":"https:\/\/woodpecker.co\/blog\/","name":"Woodpecker Blog","description":"Woodpecker Blog - Pro Tips on Cold Emails, Follow-ups, Sales &amp; Growth","publisher":{"@id":"https:\/\/woodpecker.co\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/woodpecker.co\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/woodpecker.co\/blog\/#organization","name":"Woodpecker.co","url":"https:\/\/woodpecker.co\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/woodpecker.co\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/woodpecker.co\/blog\/app\/uploads\/2015\/06\/WP_Logo_WersjaPodstawowa_Pionowa_CzarneTlo_RGB.jpg","contentUrl":"https:\/\/woodpecker.co\/blog\/app\/uploads\/2015\/06\/WP_Logo_WersjaPodstawowa_Pionowa_CzarneTlo_RGB.jpg","width":1240,"height":874,"caption":"Woodpecker.co"},"image":{"@id":"https:\/\/woodpecker.co\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/business.facebook.com\/woodpeckerapp","https:\/\/twitter.com\/woodpeckerapp","https:\/\/www.instagram.com\/woodpeckerapp\/","https:\/\/www.linkedin.com\/company\/woodpecker-co\/","https:\/\/www.youtube.com\/channel\/UCNN9wM55yaNI-KEZCfh66_A"]},{"@type":"Person","@id":"https:\/\/woodpecker.co\/blog\/#\/schema\/person\/ef0d7f439f5185f3655b45d8ad3462fd","name":"Cathy Dawiskiba","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/woodpecker.co\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5c879fd5792a7f64321f42046c8789dc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5c879fd5792a7f64321f42046c8789dc?s=96&d=mm&r=g","caption":"Cathy Dawiskiba"},"description":"Cathy started this blog a long time ago, though it seems like it was yesterday.","sameAs":["https:\/\/linkedin.com\/in\/kapatalas","https:\/\/twitter.com\/https:\/\/twitter.com\/kapatalas"],"url":"https:\/\/woodpecker.co\/blog\/es\/author\/cathy\/"}]}},"_links":{"self":[{"href":"https:\/\/woodpecker.co\/blog\/es\/wp-json\/wp\/v2\/posts\/14039"}],"collection":[{"href":"https:\/\/woodpecker.co\/blog\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/woodpecker.co\/blog\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/woodpecker.co\/blog\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/woodpecker.co\/blog\/es\/wp-json\/wp\/v2\/comments?post=14039"}],"version-history":[{"count":0,"href":"https:\/\/woodpecker.co\/blog\/es\/wp-json\/wp\/v2\/posts\/14039\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/woodpecker.co\/blog\/es\/wp-json\/wp\/v2\/media\/14041"}],"wp:attachment":[{"href":"https:\/\/woodpecker.co\/blog\/es\/wp-json\/wp\/v2\/media?parent=14039"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/woodpecker.co\/blog\/es\/wp-json\/wp\/v2\/categories?post=14039"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/woodpecker.co\/blog\/es\/wp-json\/wp\/v2\/tags?post=14039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}