{"id":14033,"date":"2022-04-11T15:41:33","date_gmt":"2022-04-11T14:41:33","guid":{"rendered":"https:\/\/woodpecker.co\/blog\/como-hacer-frente-a-las-10-objeciones-mas-comunes-en-la-venta-de-seguros\/"},"modified":"2022-04-11T15:43:18","modified_gmt":"2022-04-11T14:43:18","slug":"como-hacer-frente-a-las-10-objeciones-mas-comunes-en-la-venta-de-seguros","status":"publish","type":"post","link":"https:\/\/woodpecker.co\/blog\/es\/como-hacer-frente-a-las-10-objeciones-mas-comunes-en-la-venta-de-seguros\/","title":{"rendered":"C\u00f3mo hacer frente a las 10 objeciones m\u00e1s comunes en la venta de seguros"},"content":{"rendered":"<p><iframe loading=\"lazy\" src=\"https:\/\/w.soundcloud.com\/player\/?url=https%3A\/\/api.soundcloud.com\/tracks\/1131805072&amp;color=%23ff5500&amp;auto_play=false&amp;hide_related=false&amp;show_comments=true&amp;show_user=true&amp;show_reposts=false&amp;show_teaser=true\" width=\"100%\" height=\"166\" frameborder=\"no\" scrolling=\"no\"><\/iframe><\/p>\n<div style=\"font-size: 10px; color: #cccccc; line-break: anywhere; word-break: normal; overflow: hidden; white-space: nowrap; text-overflow: ellipsis; font-family: Interstate,Lucida Grande,Lucida Sans Unicode,Lucida Sans,Garuda,Verdana,Tahoma,sans-serif; font-weight: 100;\"><a style=\"color: #cccccc; text-decoration: none;\" title=\"Woodpecker.co\" href=\"https:\/\/soundcloud.com\/woodpeckerco\" target=\"_blank\" rel=\"noopener\">Woodpecker.co<\/a> \u00b7 <a style=\"color: #cccccc; text-decoration: none;\" title=\"How To Deal With 10 Most Common Insurance Sales Objections\" href=\"https:\/\/soundcloud.com\/woodpeckerco\/how-to-deal-with-10-most-common-insurance-sales-objections\" target=\"_blank\" rel=\"noopener\">How To Deal With 10 Most Common Insurance Sales Objections<\/a><\/div>\n<p>Si vende seguros, estar\u00e1 de acuerdo en que no hay nada peor que enfrentarse a las objeciones de venta que le impiden suscribir una nueva p\u00f3liza.<\/p>\n<p>Si quiere superar esto, ha encontrado el art\u00edculo adecuado.<\/p>\n<p>Hoy, David Duford, propietario de <a href=\"https:\/\/buylifeinsuranceforburial.com\/\">BuyLifeInsuranceForBurial.com<\/a> y autor de tres libros de ventas de seguros de gran \u00e9xito, entra en el blog de Woodpecker para detallar sus guiones de refutaci\u00f3n palabra por palabra para vencer las 10 objeciones de ventas de seguros m\u00e1s comunes.<\/p>\n<p>\u00a1Empecemos!<\/p>\n<h2>#Objeci\u00f3n n\u00ba 1: &#8220;No me interesa&#8221;.<\/h2>\n<p>Cuando alguien dice &#8220;no me interesa&#8221;, suele ser al principio del proceso de venta.<br \/>\nYo llamo a esto una objeci\u00f3n instintiva. No la tome en serio. Adem\u00e1s, \u00bfc\u00f3mo pueden saber que no est\u00e1n interesados antes de que les hayas explicado c\u00f3mo funciona tu producto?<\/p>\n<p>As\u00ed es como hay que manejarla:<\/p>\n<p><em>&#8220;No pasa nada, Sra. Prospectora. Muchas personas dicen que no est\u00e1n interesadas, pero la raz\u00f3n por la que se re\u00fanen con nosotros de todos modos es que nuestros programas son completamente diferentes de lo que ha visto. Todo lo que necesito son cinco minutos para mostrarle c\u00f3mo funciona esto, y lo que haga con la informaci\u00f3n depende de usted. \u00bfPuedo verte ma\u00f1ana a las 2:00, o ser\u00eda mejor a las 10:00?&#8221;<\/em><\/p>\n<p>\u00bfPor qu\u00e9 funciona este gui\u00f3n?<\/p>\n<p>En primer lugar, menciona que otras personas sent\u00edan lo mismo, pero aun as\u00ed aceptaron reunirse con usted. Esto da al cliente una raz\u00f3n para reunirse a pesar de su resistencia inicial.<\/p>\n<p>A continuaci\u00f3n, nos centramos en lo r\u00e1pida que es la cita, haciendo hincapi\u00e9 en que la reuni\u00f3n es poco estresante y sin ning\u00fan tipo de presi\u00f3n.<\/p>\n<p>Por \u00faltimo, cerramos con una pregunta de s\u00ed-s\u00ed: &#8220;\u00bfA qu\u00e9 hora es mejor?&#8221;. Intenta evitar hacer una pregunta de s\u00ed-s\u00ed, &#8220;\u00bfPuede reunirse ma\u00f1ana?&#8221;.<\/p>\n<p>Ver\u00e1s que el proceso es similar para algunas objeciones, as\u00ed que aseg\u00farate de remitirte para obtener m\u00e1s contexto. Y no olvides dirigirte a tu cliente de forma adecuada al principio de cada refutaci\u00f3n: Comprendo, Sr.\/Sra. Prospecto. Est\u00e1 bien&#8230;<\/p>\n<h2>#Objeci\u00f3n n\u00ba 2: &#8220;Env\u00edame informaci\u00f3n por correo&#8221;<\/h2>\n<p>Al igual que la objeci\u00f3n anterior, escuchar\u00e1s esto en persona o por tel\u00e9fono, y puedes manejarlo de la misma manera.<\/p>\n<p><em>&#8220;&#8230;Todo lo que necesito son cinco minutos para mostrarte c\u00f3mo funciona esto, y lo que hagas con la informaci\u00f3n depende de ti. \u00bfPuedo verte a las 10:00 o a las 2:00?&#8221;<\/em><\/p>\n<h2>#3 Objeci\u00f3n: &#8220;Ya tengo un seguro de vida&#8221;<\/h2>\n<p>Esta es otra objeci\u00f3n instintiva. De nuevo, intente manejarla igual que las dos primeras.<\/p>\n<p>&#8220;&#8230;S\u00f3lo necesito cinco minutos para mostrarle en qu\u00e9 se diferencia el nuestro. Lo que haga con esta informaci\u00f3n depende de usted. \u00bfPuedo verte a las 10:00 o a las 2:00?&#8221;<br \/>\n\n<aside class=\"cta-block cta-block--a-version js-cta-block ab-no-10-cta-block ab-no-11-cta-block\">\n  <p class=\"cta-block__heading u-heading-preset-md-600\">Try outbound prospecting with Woodpecker<\/p>\n  <div class=\"cta-block__form-container\">\n    <form class=\"js-cta-block-form\" action=\"https:\/\/woodpecker.co\/signup\/\" class=\"cta-block__button-only-form js-cta-block-no-input-form\">\n      \n\n\n\n\n\n\n\n\n<button class=\"c-button js-button c-button--color-main c-button--size-small u-focus-visible-outline\">\nIniciar prueba gratuita\n<\/button>    <\/form>\n    \n    <form class=\"c-input-button-form js-cta-block-form cta-block__form\" action=\"https:\/\/woodpecker.co\/signup\/\" method=\"POST\" novalidate>\n        \n  <div class=\"c-form-field js-form-field  c-input-button-form__form-field\">\n    \n    <label class=\"c-label c-form-field__label\" for=\"cta-block-form-email-354193389\">Work email<\/label>\n\n                    \n  <input class=\"c-input  js-input c-input-button-form__input\" placeholder=\"will@woodpecker.co\" name=\"email\" id=\"cta-block-form-email-354193389\" type=\"email\" \/>\n            \n    <span class=\"c-form-field__error js-error\">\n                                      Invalid email format\n        \n\n                <\/span>\n  <\/div>\n\n        <div class=\"c-input-button-form__button\">\n          \n\n\n\n\n\n\n\n\n<button class=\"cta-block__button c-button js-button c-button--color-main c-button--size-small u-focus-visible-outline\">\n                Iniciar prueba gratuita\n        \n\n<\/button>        <\/div>\n\n            <\/form>\n  <\/div>\n<\/aside><\/p>\n<h2>#4 Objeci\u00f3n: &#8220;Es demasiado caro&#8221;<\/h2>\n<p>Usted experimentar\u00e1 esta objeci\u00f3n cerca del final o al principio si est\u00e1 precalificando a su cliente, y ellos est\u00e1n en un presupuesto.<\/p>\n<p>Para ello, averig\u00fce el presupuesto de su cliente lo antes posible y adapte su oferta a \u00e9l. Normalmente, cuando los clientes se quejan del precio es porque T\u00da no has conseguido crear valor.<br \/>\nSi siguen objetando incluso despu\u00e9s de haber creado valor y ajustado su presupuesto, esto es lo que debes hacer:<\/p>\n<p><em>&#8220;&#8230;O\u00edmos esto a menudo. Pero usted ha dicho que necesita un seguro. Y al final, \u00bfqu\u00e9 va a costar m\u00e1s? Pagar la prima o evitar el seguro y acabar necesitando desesperadamente la cobertura debido a un accidente repentino y extra\u00f1o. No resolver\u00e1s este problema si no contratas un seguro. S\u00f3lo empeorar\u00e1 el problema. \u00bfPor qu\u00e9 no empezamos con este plan? \u00bfO prefieres ver un presupuesto m\u00e1s bajo?&#8221;<\/em><\/p>\n<h2>#5 Objeci\u00f3n &#8211; D\u00e9jeme pensarlo<\/h2>\n<p>A menudo escuchar\u00e1 esto al final de una llamada. En el negocio, lo llamamos &#8220;objeci\u00f3n de cortina de humo&#8221;. En pocas palabras, es una excusa, una forma educada de evitar explicar el verdadero problema. Para atajarla, hay que desenterrar cu\u00e1l es el problema real.<\/p>\n<p>Cuando un cliente potencial dice: <em>&#8220;D\u00e9jame pensarlo&#8221;. T\u00fa dices: &#8220;&#8230;Cuando dices que necesitas pensarlo, \u00bfa qu\u00e9 te refieres?&#8221;.<\/em><\/p>\n<p>Si el cliente potencial contesta, t\u00fa respondes:<em> &#8220;Bien. M\u00e1s all\u00e1 de X, \u00bfhay alguna otra raz\u00f3n por la que no har\u00edas negocios hoy&#8230;? Y si puedo ayudarle a resolver X, \u00bfhay alguna raz\u00f3n por la que no seguir\u00eda adelante con este pl<\/em>an?&#8221;.<\/p>\n<p>Al hacer esto, se a\u00edsla la objeci\u00f3n, se confirma que no hay otros problemas y se asegura el compromiso de seguir adelante.<\/p>\n<h2>Objeci\u00f3n #6 &#8211; D\u00e9jame hablar con mis hijos<\/h2>\n<p>Otra objeci\u00f3n de cortina de humo que se suele escuchar al final de la llamada.<br \/>\nSi se encuentra con esta objeci\u00f3n a menudo durante los lanzamientos, debe centrarse en establecer una relaci\u00f3n desde el principio y ganarse la confianza de su cliente.<\/p>\n<p>Cuando alguien quiere confirmar el plan con sus hijos, especialmente los mayores, suele significar que no te has ganado su confianza. Esto es lo que te recomiendo que digas a continuaci\u00f3n<\/p>\n<p><em>&#8220;&#8230;entiendo que quieras hablar de esto con tus hijos, pero has dicho que necesitas cobertura AHORA. Si algo malo sucede entre ahora y la resoluci\u00f3n de este asunto, tus hijos tendr\u00e1n que cubrir los gastos del funeral. La mayor\u00eda de los padres con los que hablo quieren evitar que esto ocurra. Seguramente usted piensa lo mismo, ya que no deber\u00eda ser su responsabilidad.<\/em><br \/>\n<em>Mire, Sra. Jones. Usted es una persona lo suficientemente sabia como para tomar sus propias decisiones. Y creo que ambos estaremos de acuerdo en que cuanto antes resuelva esto, mejor. Vamos a seguir adelante y comenzar con un plan hoy. \u00bfQui\u00e9n quieres que sea tu beneficiario?&#8221;<\/em><\/p>\n<h2>#7 Objeci\u00f3n &#8211; D\u00e9jeme hablar con mi abogado o contable<\/h2>\n<p>Escuchar\u00e1 esto sobre todo con los propietarios de empresas. El truco consiste en aceptar que es importante averiguar lo que tiene que decir su abogado o contable.<\/p>\n<p>Famosos vendedores de seguros como Ben Feldman y Frank Betcher utilizan estas estrategias para hacer avanzar la pelota y conseguir una solicitud.<\/p>\n<p>Pruebe este enfoque:<\/p>\n<p><em>&#8220;&#8230;\u00bfPor qu\u00e9 no hacemos esto? Tambi\u00e9n creo que es importante que hable con su contable o abogado y les proporcione informaci\u00f3n precisa para que puedan ayudarle a tomar la decisi\u00f3n correcta. Mientras tanto, lo que tenemos aqu\u00ed es simplemente una propuesta.<\/em><\/p>\n<p><em>En este momento, ni siquiera puedo garantizarte que vayas a cumplir los requisitos hasta que completemos el proceso. Esta es mi propuesta. No necesito ning\u00fan dinero de usted hoy. Y si decides no seguir adelante, no pasa nada. Pero si se toma en serio lo de conseguir un seguro y quiere honestamente una opini\u00f3n precisa de su contable o abogado, debemos calificarle primero.<\/em><\/p>\n<p><em>Le enviaremos a alguien. De forma gratuita. Y trabajaremos alrededor de su horario. As\u00ed que hagamos eso primero. Entonces tendr\u00e1 toda la informaci\u00f3n y podr\u00e1 obtener una opini\u00f3n honesta e informada de su contable o abogado. De lo contrario, no podr\u00e1 proporcionarles todos los datos. Entonces, \u00bfc\u00f3mo te sientes para seguir adelante?<\/em><br \/>\n\n<aside class=\"cta-block cta-block--a-version js-cta-block ab-no-10-cta-block ab-no-11-cta-block\">\n  <p class=\"cta-block__heading u-heading-preset-md-600\">Run more efficient outreach campaigns<\/p>\n  <div class=\"cta-block__form-container\">\n    <form class=\"js-cta-block-form\" action=\"https:\/\/woodpecker.co\/signup\/\" class=\"cta-block__button-only-form js-cta-block-no-input-form\">\n      \n\n\n\n\n\n\n\n\n<button class=\"c-button js-button c-button--color-main c-button--size-small u-focus-visible-outline\">\nIniciar prueba gratuita\n<\/button>    <\/form>\n    \n    <form class=\"c-input-button-form js-cta-block-form cta-block__form\" action=\"https:\/\/woodpecker.co\/signup\/\" method=\"POST\" novalidate>\n        \n  <div class=\"c-form-field js-form-field  c-input-button-form__form-field\">\n    \n    <label class=\"c-label c-form-field__label\" for=\"cta-block-form-email-634517236\">Work email<\/label>\n\n                    \n  <input class=\"c-input  js-input c-input-button-form__input\" placeholder=\"will@woodpecker.co\" name=\"email\" id=\"cta-block-form-email-634517236\" type=\"email\" \/>\n            \n    <span class=\"c-form-field__error js-error\">\n                                      Invalid email format\n        \n\n                <\/span>\n  <\/div>\n\n        <div class=\"c-input-button-form__button\">\n          \n\n\n\n\n\n\n\n\n<button class=\"cta-block__button c-button js-button c-button--color-main c-button--size-small u-focus-visible-outline\">\n                Iniciar prueba gratuita\n        \n\n<\/button>        <\/div>\n\n            <\/form>\n  <\/div>\n<\/aside><\/p>\n<h2>#8 Objeci\u00f3n &#8211; No creo en los seguros<\/h2>\n<p>Esta es un poco m\u00e1s dif\u00edcil. Lo mejor es asumir que no entienden c\u00f3mo funcionan los seguros.<\/p>\n<p>Lo m\u00e1s probable es que esta objeci\u00f3n tenga una buena raz\u00f3n. Tal vez un amigo o un pariente fue defraudado por una compa\u00f1\u00eda de seguros en el pasado.<\/p>\n<p>Si al concertar la cita, ya sea cara a cara o por tel\u00e9fono, escuchas esto, esto es lo que debes hacer:<\/p>\n<p><em>&#8220;&#8230;Mucha gente dice esto. Pero dedique cinco minutos a mostrarle en qu\u00e9 consiste mi seguro. Lo que haga con esta informaci\u00f3n depende de usted. \u00bfLe viene mejor una reuni\u00f3n a las 2:00 o a las 4:00?&#8221;<\/em><\/p>\n<h2>#9 Objeci\u00f3n &#8211; Me gusta pero no quiero comprarlo ahora<\/h2>\n<p>Algunos prospectos dir\u00e1n que est\u00e1n interesados pero no est\u00e1n listos para comprometerse. El problema aqu\u00ed es la &#8220;urgencia&#8221;. Lo m\u00e1s probable es que usted no les haya dado suficiente valor o no les haya explicado la importancia de tener un seguro.<\/p>\n<p>Solemos aconsejar a los agentes de seguros de vida que le digan al cliente que se imagine el coche f\u00fanebre arrimado al porche. Suena un poco extremo, pero para beneficiarse del seguro de vida, hay que&#8230; bueno, morir. Y es comprensible que la gente tenga miedo de imagin\u00e1rselo.<\/p>\n<p>Para vencer esta resistencia, intente esto:<\/p>\n<p><em>&#8220;&#8230;Pero en realidad, nadie puede prometerte el ma\u00f1ana. T\u00fa y yo sabemos que pueden ocurrir cosas malas sin previo aviso. E incluso si tienes suerte y s\u00f3lo te lesionas o enfermas, eso puede afectar a tu capacidad de obtener cobertura. Es posible que m\u00e1s adelante no puedas optar a este plan.<\/em><br \/>\n<em>Y, no arreglar\u00e1s este asunto evitando el problema. La soluci\u00f3n es empezar con un plan lo antes posible. Vamos a contratar este plan, empezarlo el mes que viene, y luego podr\u00e1 relajarse. \u00bfQui\u00e9n quieres que sea tu beneficiario?&#8221;<\/em><\/p>\n<h2>#10 Objeci\u00f3n &#8211; No me gustan los giros bancarios<\/h2>\n<p>Probablemente oir\u00e1 esto muchas veces, ya que las compa\u00f1\u00edas de seguros exigen un giro bancario. Pruebe esta estrategia:<\/p>\n<p><em>&#8220;&#8230;\u00bfPuede pagar con varios meses de antelaci\u00f3n? Si puede conseguir que el cheque se pague hoy con un pago trimestral o mayor, entonces ac\u00e9ptelo&#8221;.<\/em><\/p>\n<p>Si no pueden, entonces har\u00eda lo siguiente:<\/p>\n<p><em>&#8220;Bueno, por desgracia, todas estas empresas requieren giros bancarios. Y, no hay nada que pueda hacer para ayudarte con eso. Las empresas ya no env\u00edan cartas para los pagos mensuales.<\/em><\/p>\n<p><em>Pero, podemos establecer un calendario de pagos despu\u00e9s de que te paguen. De esta manera, nunca se te cobrar\u00e1 cuando no tengas el dinero. \u00bfPodemos seguir adelante con eso?&#8221;<\/em><\/p>\n<p>Afronta esas 10 objeciones de venta habituales y cierra m\u00e1s tratos<\/p>\n<p>Y as\u00ed concluye la forma en que mis agentes y yo abordamos estas objeciones comunes de venta de seguros. Espero que hayas sacado algo en claro de la lectura de este art\u00edculo y que, en \u00faltima instancia, puedas aumentar tus ventas y ayudar a m\u00e1s personas.<br \/>\nGracias por leerlo.<\/p>\n<p>\n<aside class=\"cta-block cta-block--a-version js-cta-block ab-no-10-cta-block ab-no-11-cta-block\">\n  <p class=\"cta-block__heading u-heading-preset-md-600\">Try outbound prospecting<br \/>\nwith Woodpecker<\/p>\n  <div class=\"cta-block__form-container\">\n    <form class=\"js-cta-block-form\" action=\"https:\/\/woodpecker.co\/signup\/\" class=\"cta-block__button-only-form js-cta-block-no-input-form\">\n      \n\n\n\n\n\n\n\n\n<button class=\"c-button js-button c-button--color-main c-button--size-small u-focus-visible-outline\">\nIniciar prueba gratuita\n<\/button>    <\/form>\n    \n    <form class=\"c-input-button-form js-cta-block-form cta-block__form\" action=\"https:\/\/woodpecker.co\/signup\/\" method=\"POST\" novalidate>\n        \n  <div class=\"c-form-field js-form-field  c-input-button-form__form-field\">\n    \n    <label class=\"c-label c-form-field__label\" for=\"cta-block-form-email-1622461384\">Work email<\/label>\n\n                    \n  <input class=\"c-input  js-input c-input-button-form__input\" placeholder=\"will@woodpecker.co\" name=\"email\" id=\"cta-block-form-email-1622461384\" type=\"email\" \/>\n            \n    <span class=\"c-form-field__error js-error\">\n                                      Invalid email format\n        \n\n                <\/span>\n  <\/div>\n\n        <div class=\"c-input-button-form__button\">\n          \n\n\n\n\n\n\n\n\n<button class=\"cta-block__button c-button js-button c-button--color-main c-button--size-small u-focus-visible-outline\">\n                Iniciar prueba gratuita\n        \n\n<\/button>        <\/div>\n\n            <\/form>\n  <\/div>\n<\/aside><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si vende seguros, estar\u00e1 de acuerdo en que no hay nada peor que enfrentarse a las objeciones de venta que le impiden suscribir una nueva p\u00f3liza.<\/p>\n<p>Si quiere superar esto, ha encontrado el art\u00edculo adecuado.<\/p>\n<p>Hoy, David Duford, propietario de BuyLifeInsuranceForBurial.com y autor de tres libros de ventas de seguros de gran \u00e9xito, entra en el blog de Woodpecker para detallar sus guiones de refutaci\u00f3n palabra por palabra para vencer las 10 objeciones de ventas de seguros m\u00e1s comunes.<\/p>\n","protected":false},"author":31,"featured_media":14034,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[65],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>C\u00f3mo hacer frente a las 10 objeciones de venta m\u00e1s comunes en los seguros<\/title>\n<meta name=\"description\" content=\"Si vende seguros, conoce el dolor que supone enfrentarse a las objeciones de venta que le impiden cerrar el trato. Comprueba c\u00f3mo rebatir las 10 m\u00e1s comunes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/woodpecker.co\/blog\/es\/como-hacer-frente-a-las-10-objeciones-mas-comunes-en-la-venta-de-seguros\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo hacer frente a las 10 objeciones de venta m\u00e1s comunes en los seguros\" \/>\n<meta property=\"og:description\" content=\"Si vende seguros, conoce el dolor que supone enfrentarse a las objeciones de venta que le impiden cerrar el trato. Comprueba c\u00f3mo rebatir las 10 m\u00e1s comunes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/woodpecker.co\/blog\/es\/como-hacer-frente-a-las-10-objeciones-mas-comunes-en-la-venta-de-seguros\/\" \/>\n<meta property=\"og:site_name\" content=\"Woodpecker Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/business.facebook.com\/woodpeckerapp\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-11T14:41:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-11T14:43:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/woodpecker.co\/blog\/app\/uploads\/2020\/10\/29.10.2020-How_To_Deal_With_10_Most_Common_Insurance_Sales_Objections-blog-01.png\" \/>\n\t<meta property=\"og:image:width\" content=\"650\" \/>\n\t<meta property=\"og:image:height\" content=\"391\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"David Dufford\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@woodpeckerapp\" \/>\n<meta name=\"twitter:site\" content=\"@woodpeckerapp\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/woodpecker.co\/blog\/es\/como-hacer-frente-a-las-10-objeciones-mas-comunes-en-la-venta-de-seguros\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/woodpecker.co\/blog\/es\/como-hacer-frente-a-las-10-objeciones-mas-comunes-en-la-venta-de-seguros\/\"},\"author\":{\"name\":\"David Dufford\",\"@id\":\"https:\/\/woodpecker.co\/blog\/#\/schema\/person\/767182599ba60a6378426f32c16aa28b\"},\"headline\":\"C\u00f3mo hacer frente a las 10 objeciones m\u00e1s comunes en la venta de seguros\",\"datePublished\":\"2022-04-11T14:41:33+00:00\",\"dateModified\":\"2022-04-11T14:43:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/woodpecker.co\/blog\/es\/como-hacer-frente-a-las-10-objeciones-mas-comunes-en-la-venta-de-seguros\/\"},\"wordCount\":1766,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/woodpecker.co\/blog\/#organization\"},\"articleSection\":[\"Sales &amp; growth\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/woodpecker.co\/blog\/es\/como-hacer-frente-a-las-10-objeciones-mas-comunes-en-la-venta-de-seguros\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/woodpecker.co\/blog\/es\/como-hacer-frente-a-las-10-objeciones-mas-comunes-en-la-venta-de-seguros\/\",\"url\":\"https:\/\/woodpecker.co\/blog\/es\/como-hacer-frente-a-las-10-objeciones-mas-comunes-en-la-venta-de-seguros\/\",\"name\":\"C\u00f3mo hacer frente a las 10 objeciones de venta m\u00e1s comunes en los seguros\",\"isPartOf\":{\"@id\":\"https:\/\/woodpecker.co\/blog\/#website\"},\"datePublished\":\"2022-04-11T14:41:33+00:00\",\"dateModified\":\"2022-04-11T14:43:18+00:00\",\"description\":\"Si vende seguros, conoce el dolor que supone enfrentarse a las objeciones de venta que le impiden cerrar el trato. Comprueba c\u00f3mo rebatir las 10 m\u00e1s comunes.\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/woodpecker.co\/blog\/es\/como-hacer-frente-a-las-10-objeciones-mas-comunes-en-la-venta-de-seguros\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/woodpecker.co\/blog\/#website\",\"url\":\"https:\/\/woodpecker.co\/blog\/\",\"name\":\"Woodpecker Blog\",\"description\":\"Woodpecker Blog - Pro Tips on Cold Emails, Follow-ups, Sales &amp; Growth\",\"publisher\":{\"@id\":\"https:\/\/woodpecker.co\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/woodpecker.co\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/woodpecker.co\/blog\/#organization\",\"name\":\"Woodpecker.co\",\"url\":\"https:\/\/woodpecker.co\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/woodpecker.co\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/woodpecker.co\/blog\/app\/uploads\/2015\/06\/WP_Logo_WersjaPodstawowa_Pionowa_CzarneTlo_RGB.jpg\",\"contentUrl\":\"https:\/\/woodpecker.co\/blog\/app\/uploads\/2015\/06\/WP_Logo_WersjaPodstawowa_Pionowa_CzarneTlo_RGB.jpg\",\"width\":1240,\"height\":874,\"caption\":\"Woodpecker.co\"},\"image\":{\"@id\":\"https:\/\/woodpecker.co\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/business.facebook.com\/woodpeckerapp\",\"https:\/\/twitter.com\/woodpeckerapp\",\"https:\/\/www.instagram.com\/woodpeckerapp\/\",\"https:\/\/www.linkedin.com\/company\/woodpecker-co\/\",\"https:\/\/www.youtube.com\/channel\/UCNN9wM55yaNI-KEZCfh66_A\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/woodpecker.co\/blog\/#\/schema\/person\/767182599ba60a6378426f32c16aa28b\",\"name\":\"David Dufford\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/woodpecker.co\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/dd0bd95b8aec785ef20f075ce12aafde?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/dd0bd95b8aec785ef20f075ce12aafde?s=96&d=mm&r=g\",\"caption\":\"David Dufford\"},\"description\":\"David Duford owns BuyLifeInsuranceForBurial.com, a virtual insurance agency helping seniors find affordable final expense burial insurance. He is the author of 3 best-selling insurance sales and marketing books, including \u201cThe Official Guide To Selling Insurance For New Agents, \u201cThe Official Guide To Selling Final Expense Insurance,\u201d and \u201cInterviews With Top Producing Insurance Agents.\u201d David is also a YouTube Influencer in insurance sales with over 16,000 subscribers and more than 1.7 million total views.\",\"url\":\"https:\/\/woodpecker.co\/blog\/es\/author\/david-duford\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f3mo hacer frente a las 10 objeciones de venta m\u00e1s comunes en los seguros","description":"Si vende seguros, conoce el dolor que supone enfrentarse a las objeciones de venta que le impiden cerrar el trato. Comprueba c\u00f3mo rebatir las 10 m\u00e1s comunes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/woodpecker.co\/blog\/es\/como-hacer-frente-a-las-10-objeciones-mas-comunes-en-la-venta-de-seguros\/","og_locale":"es_ES","og_type":"article","og_title":"C\u00f3mo hacer frente a las 10 objeciones de venta m\u00e1s comunes en los seguros","og_description":"Si vende seguros, conoce el dolor que supone enfrentarse a las objeciones de venta que le impiden cerrar el trato. Comprueba c\u00f3mo rebatir las 10 m\u00e1s comunes.","og_url":"https:\/\/woodpecker.co\/blog\/es\/como-hacer-frente-a-las-10-objeciones-mas-comunes-en-la-venta-de-seguros\/","og_site_name":"Woodpecker Blog","article_publisher":"https:\/\/business.facebook.com\/woodpeckerapp","article_published_time":"2022-04-11T14:41:33+00:00","article_modified_time":"2022-04-11T14:43:18+00:00","og_image":[{"width":650,"height":391,"url":"https:\/\/woodpecker.co\/blog\/app\/uploads\/2020\/10\/29.10.2020-How_To_Deal_With_10_Most_Common_Insurance_Sales_Objections-blog-01.png","type":"image\/png"}],"author":"David Dufford","twitter_card":"summary_large_image","twitter_creator":"@woodpeckerapp","twitter_site":"@woodpeckerapp","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/woodpecker.co\/blog\/es\/como-hacer-frente-a-las-10-objeciones-mas-comunes-en-la-venta-de-seguros\/#article","isPartOf":{"@id":"https:\/\/woodpecker.co\/blog\/es\/como-hacer-frente-a-las-10-objeciones-mas-comunes-en-la-venta-de-seguros\/"},"author":{"name":"David Dufford","@id":"https:\/\/woodpecker.co\/blog\/#\/schema\/person\/767182599ba60a6378426f32c16aa28b"},"headline":"C\u00f3mo hacer frente a las 10 objeciones m\u00e1s comunes en la venta de seguros","datePublished":"2022-04-11T14:41:33+00:00","dateModified":"2022-04-11T14:43:18+00:00","mainEntityOfPage":{"@id":"https:\/\/woodpecker.co\/blog\/es\/como-hacer-frente-a-las-10-objeciones-mas-comunes-en-la-venta-de-seguros\/"},"wordCount":1766,"commentCount":0,"publisher":{"@id":"https:\/\/woodpecker.co\/blog\/#organization"},"articleSection":["Sales &amp; growth"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/woodpecker.co\/blog\/es\/como-hacer-frente-a-las-10-objeciones-mas-comunes-en-la-venta-de-seguros\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/woodpecker.co\/blog\/es\/como-hacer-frente-a-las-10-objeciones-mas-comunes-en-la-venta-de-seguros\/","url":"https:\/\/woodpecker.co\/blog\/es\/como-hacer-frente-a-las-10-objeciones-mas-comunes-en-la-venta-de-seguros\/","name":"C\u00f3mo hacer frente a las 10 objeciones de venta m\u00e1s comunes en los seguros","isPartOf":{"@id":"https:\/\/woodpecker.co\/blog\/#website"},"datePublished":"2022-04-11T14:41:33+00:00","dateModified":"2022-04-11T14:43:18+00:00","description":"Si vende seguros, conoce el dolor que supone enfrentarse a las objeciones de venta que le impiden cerrar el trato. Comprueba c\u00f3mo rebatir las 10 m\u00e1s comunes.","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/woodpecker.co\/blog\/es\/como-hacer-frente-a-las-10-objeciones-mas-comunes-en-la-venta-de-seguros\/"]}]},{"@type":"WebSite","@id":"https:\/\/woodpecker.co\/blog\/#website","url":"https:\/\/woodpecker.co\/blog\/","name":"Woodpecker Blog","description":"Woodpecker Blog - Pro Tips on Cold Emails, Follow-ups, Sales &amp; Growth","publisher":{"@id":"https:\/\/woodpecker.co\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/woodpecker.co\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/woodpecker.co\/blog\/#organization","name":"Woodpecker.co","url":"https:\/\/woodpecker.co\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/woodpecker.co\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/woodpecker.co\/blog\/app\/uploads\/2015\/06\/WP_Logo_WersjaPodstawowa_Pionowa_CzarneTlo_RGB.jpg","contentUrl":"https:\/\/woodpecker.co\/blog\/app\/uploads\/2015\/06\/WP_Logo_WersjaPodstawowa_Pionowa_CzarneTlo_RGB.jpg","width":1240,"height":874,"caption":"Woodpecker.co"},"image":{"@id":"https:\/\/woodpecker.co\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/business.facebook.com\/woodpeckerapp","https:\/\/twitter.com\/woodpeckerapp","https:\/\/www.instagram.com\/woodpeckerapp\/","https:\/\/www.linkedin.com\/company\/woodpecker-co\/","https:\/\/www.youtube.com\/channel\/UCNN9wM55yaNI-KEZCfh66_A"]},{"@type":"Person","@id":"https:\/\/woodpecker.co\/blog\/#\/schema\/person\/767182599ba60a6378426f32c16aa28b","name":"David Dufford","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/woodpecker.co\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/dd0bd95b8aec785ef20f075ce12aafde?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dd0bd95b8aec785ef20f075ce12aafde?s=96&d=mm&r=g","caption":"David Dufford"},"description":"David Duford owns BuyLifeInsuranceForBurial.com, a virtual insurance agency helping seniors find affordable final expense burial insurance. He is the author of 3 best-selling insurance sales and marketing books, including \u201cThe Official Guide To Selling Insurance For New Agents, \u201cThe Official Guide To Selling Final Expense Insurance,\u201d and \u201cInterviews With Top Producing Insurance Agents.\u201d David is also a YouTube Influencer in insurance sales with over 16,000 subscribers and more than 1.7 million total views.","url":"https:\/\/woodpecker.co\/blog\/es\/author\/david-duford\/"}]}},"_links":{"self":[{"href":"https:\/\/woodpecker.co\/blog\/es\/wp-json\/wp\/v2\/posts\/14033"}],"collection":[{"href":"https:\/\/woodpecker.co\/blog\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/woodpecker.co\/blog\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/woodpecker.co\/blog\/es\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/woodpecker.co\/blog\/es\/wp-json\/wp\/v2\/comments?post=14033"}],"version-history":[{"count":1,"href":"https:\/\/woodpecker.co\/blog\/es\/wp-json\/wp\/v2\/posts\/14033\/revisions"}],"predecessor-version":[{"id":14038,"href":"https:\/\/woodpecker.co\/blog\/es\/wp-json\/wp\/v2\/posts\/14033\/revisions\/14038"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/woodpecker.co\/blog\/es\/wp-json\/wp\/v2\/media\/14034"}],"wp:attachment":[{"href":"https:\/\/woodpecker.co\/blog\/es\/wp-json\/wp\/v2\/media?parent=14033"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/woodpecker.co\/blog\/es\/wp-json\/wp\/v2\/categories?post=14033"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/woodpecker.co\/blog\/es\/wp-json\/wp\/v2\/tags?post=14033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}