{"id":14006,"date":"2022-04-11T10:06:51","date_gmt":"2022-04-11T09:06:51","guid":{"rendered":"https:\/\/woodpecker.co\/blog\/cuales-son-los-limites-de-envio-de-correo-electronico-de-los-distintos-proveedores-de-servicios-de-correo-electronico\/"},"modified":"2022-04-11T10:47:08","modified_gmt":"2022-04-11T09:47:08","slug":"cuales-son-los-limites-de-envio-de-correo-electronico-de-los-distintos-proveedores-de-servicios-de-correo-electronico","status":"publish","type":"post","link":"https:\/\/woodpecker.co\/blog\/es\/cuales-son-los-limites-de-envio-de-correo-electronico-de-los-distintos-proveedores-de-servicios-de-correo-electronico\/","title":{"rendered":"\u00bfCu\u00e1les son los l\u00edmites de env\u00edo de correo electr\u00f3nico de los distintos proveedores de servicios de correo electr\u00f3nico?"},"content":{"rendered":"<p>Tienes que saber esto. Especialmente si haces difusi\u00f3n por correo electr\u00f3nico. Cada proveedor de servicios de correo electr\u00f3nico tiene sus propios l\u00edmites de env\u00edo. Los l\u00edmites pueden ser diarios, por hora, y a veces tambi\u00e9n por minuto. Si est\u00e1 enviando campa\u00f1as de correo electr\u00f3nico en fr\u00edo sin ser consciente de los l\u00edmites de su proveedor de correo electr\u00f3nico, su cuenta de correo electr\u00f3nico puede ser bloqueada antes de que se d\u00e9 cuenta.<\/p>\n<p>En esta entrada del blog, encontrar\u00e1s informaci\u00f3n sobre:<\/p>\n<ul>\n<li>cu\u00e1ntos correos electr\u00f3nicos puede enviar Gmail al d\u00eda,<\/li>\n<li>cu\u00e1ntos correos electr\u00f3nicos puede enviar a la vez con Yahoo,<\/li>\n<li>cu\u00e1ntos correos electr\u00f3nicos puede enviar Outlook.com a la vez,<\/li>\n<li>cu\u00e1les son los l\u00edmites de env\u00edo de correo electr\u00f3nico de algunos otros hosts de correo electr\u00f3nico populares,<\/li>\n<li>cu\u00e1ntos correos electr\u00f3nicos se consideran spam y c\u00f3mo evitar entrar en la lista negra.<\/li>\n<\/ul>\n<p>Si est\u00e1s buscando una respuesta a cualquiera de las preguntas anteriores, has venido al lugar correcto.<\/p>\n<p>Y si prefieres ver en lugar de leer, aqu\u00ed tienes un breve v\u00eddeo basado en el contenido de esta entrada del blog:<\/p>\n<p><center><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/MXoAO2t99S0\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/center>&nbsp;<\/p>\n<p>Y aqu\u00ed hay una versi\u00f3n de audio:<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/w.soundcloud.com\/player\/?url=https%3A\/\/api.soundcloud.com\/tracks\/1125533692&amp;color=%23ff5500&amp;auto_play=false&amp;hide_related=false&amp;show_comments=true&amp;show_user=true&amp;show_reposts=false&amp;show_teaser=true\" width=\"100%\" height=\"166\" frameborder=\"no\" scrolling=\"no\"><\/iframe><\/p>\n<p><a style=\"color: #cccccc; text-decoration: none;\" title=\"Woodpecker.co\" href=\"https:\/\/soundcloud.com\/woodpeckerco\" target=\"_blank\" rel=\"noopener\">Woodpecker.co<\/a> \u00b7 <a style=\"color: #cccccc; text-decoration: none;\" title=\"What Are Email Sending Limits of Various Email Service Providers?\" href=\"https:\/\/soundcloud.com\/woodpeckerco\/what-are-email-sending-limits-of-various-email-service-providers\" target=\"_blank\" rel=\"noopener\">What Are Email Sending Limits of Various Email Service Providers?<\/a><\/p>\n<h2>\u00bfPor qu\u00e9 es crucial conocer los l\u00edmites de env\u00edo de emails?<\/h2>\n<p>Si est\u00e1 enviando sus correos electr\u00f3nicos fr\u00edos utilizando herramientas como Woodpecker, que env\u00eda correos electr\u00f3nicos desde su propio buz\u00f3n de correo (su propio <a href=\"https:\/\/woodpecker.co\/blog\/smtp-imap\/\">SMTP<\/a>), los l\u00edmites de su proveedor de servicios de<a href=\"https:\/\/woodpecker.co\/blog\/how-to-write-a-cold-email-that-actually-works-six-step-tutorial\/\"> correo electr\u00f3nico<\/a> son los que debe vigilar al configurar sus campa\u00f1as de correo electr\u00f3nico fr\u00edo.<\/p>\n<p>Aunque Woodpecker limita el n\u00famero de correos electr\u00f3nicos que puede enviar<a href=\"https:\/\/woodpecker.co\/pricing\/\"> en funci\u00f3n del plan de precios<\/a> que elija, son los l\u00edmites de su proveedor los que debe tener m\u00e1s en cuenta. Enviar demasiados correos electr\u00f3nicos al d\u00eda (o a veces incluso demasiados por hora, o por minuto) puede hacer que tu cuenta de correo electr\u00f3nico se bloquee, es decir, que no puedas enviar ning\u00fan tipo de correo electr\u00f3nico desde esta cuenta durante 24 horas o m\u00e1s.<\/p>\n<p>Si conoces los l\u00edmites, y configuras tu tiempo de entrega y el n\u00famero de emails enviados diariamente por campa\u00f1a de acuerdo a esos l\u00edmites, tus campa\u00f1as se enviar\u00e1n sin problemas seg\u00fan lo planeado y tus emails no ser\u00e1n considerados SPAM- siempre y cuando no est\u00e9s enviando contenido de baja calidad y sin ning\u00fan tipo de personalizaci\u00f3n.<\/p>\n<p>Si est\u00e1s enviando spam o cualquier cosa que sea considerada como tal por tus destinatarios, te pondr\u00e1n en la lista negra de todos modos y probablemente antes de que alcances tu l\u00edmite de env\u00edo diario. Recuerde: la <a href=\"https:\/\/woodpecker.co\/blog\/deliverability-checks\/\">entregabilidad<\/a> de sus correos electr\u00f3nicos fr\u00edos tambi\u00e9n es crucial si quiere evitar ser incluido en la lista negra.<\/p>\n<p>Los l\u00edmites de env\u00edo de correos electr\u00f3nicos impuestos por su proveedor son para todos los mensajes enviados desde su direcci\u00f3n. Por eso, si tiene varios seguimientos planificados dentro de su campa\u00f1a, debe tener en cuenta que al cabo de unos d\u00edas o semanas, no s\u00f3lo se pondr\u00e1n en cola de env\u00edo sus correos de primer contacto al d\u00eda, sino tambi\u00e9n una serie de seguimientos. Como todos los tipos de correos electr\u00f3nicos programados se solapan, los l\u00edmites pueden superarse f\u00e1cilmente. Lo mismo ocurre si se env\u00edan varias campa\u00f1as desde la misma direcci\u00f3n de correo electr\u00f3nico al mismo tiempo.<\/p>\n<h2>\u00bfCu\u00e1les son los l\u00edmites de env\u00edo de correos electr\u00f3nicos de los distintos hosts de correo electr\u00f3nico?<\/h2>\n<p><strong>IMPORTANTE:<\/strong><br \/>\nEsta entrada del blog se actualiza de vez en cuando, pero ten en cuenta que los l\u00edmites pueden cambiar mientras tanto. Por lo tanto, es crucial seguir los enlaces de los recursos directos para asegurarse de obtener informaci\u00f3n actualizada.<\/p>\n<p><em>Si tu proveedor de correo electr\u00f3nico no est\u00e1 en la lista, h\u00e1zmelo saber en los comentarios para que pueda a\u00f1adirlo.<\/em><br \/>\n\n<aside class=\"cta-block cta-block--a-version js-cta-block ab-no-10-cta-block ab-no-11-cta-block\">\n  <p class=\"cta-block__heading u-heading-preset-md-600\">Try every Woodpecker feature for free<\/p>\n  <div class=\"cta-block__form-container\">\n    <form class=\"js-cta-block-form\" action=\"https:\/\/woodpecker.co\/signup\/\" class=\"cta-block__button-only-form js-cta-block-no-input-form\">\n      \n\n\n\n\n\n\n\n\n<button class=\"c-button js-button c-button--color-main c-button--size-small u-focus-visible-outline\">\nIniciar prueba gratuita\n<\/button>    <\/form>\n    \n    <form class=\"c-input-button-form js-cta-block-form cta-block__form\" action=\"https:\/\/woodpecker.co\/signup\/\" method=\"POST\" novalidate>\n        \n  <div class=\"c-form-field js-form-field  c-input-button-form__form-field\">\n    \n    <label class=\"c-label c-form-field__label\" for=\"cta-block-form-email-266841022\">Work email<\/label>\n\n                    \n  <input class=\"c-input  js-input c-input-button-form__input\" placeholder=\"will@woodpecker.co\" name=\"email\" id=\"cta-block-form-email-266841022\" type=\"email\" \/>\n            \n    <span class=\"c-form-field__error js-error\">\n                                      Invalid email format\n        \n\n                <\/span>\n  <\/div>\n\n        <div class=\"c-input-button-form__button\">\n          \n\n\n\n\n\n\n\n\n<button class=\"cta-block__button c-button js-button c-button--color-main c-button--size-small u-focus-visible-outline\">\n                Iniciar prueba gratuita\n        \n\n<\/button>        <\/div>\n\n            <\/form>\n  <\/div>\n<\/aside><\/p>\n<h3>L\u00edmite de env\u00edo de correo electr\u00f3nico gratuito de Gmail<\/h3>\n<p><strong>Por d\u00eda<\/strong>: 100 mensajes como m\u00e1ximo a trav\u00e9s de SMTP (pero 500 correos electr\u00f3nicos a trav\u00e9s del navegador).<\/p>\n<p><strong>Por hora<\/strong>: No hay informaci\u00f3n oficial. Sin embargo, seg\u00fan nuestra experiencia, es bueno no enviar m\u00e1s de 20 mensajes por hora desde una cuenta gratuita de Gmail.<\/p>\n<p><strong>Informaci\u00f3n adicional<\/strong>: Si superas la cuota de env\u00edo de Gmail, tu cuenta se bloquear\u00e1 durante 1-24 horas. Por lo general, no recomendamos enviar campa\u00f1as de correo electr\u00f3nico en fr\u00edo desde una cuenta gratuita de Gmail normal, sino crear una direcci\u00f3n en un dominio independiente mediante Workspace Google (anteriormente G Suite, un servicio de correo electr\u00f3nico para empresas de Google). Esto le da mayores oportunidades en cuanto al volumen de alcance y m\u00e1s control sobre su configuraci\u00f3n de env\u00edo. Lea m\u00e1s sobre la diferencia entre una cuenta de correo electr\u00f3nico gratuita y un correo electr\u00f3nico de dominio personalizado <a href=\"https:\/\/woodpecker.co\/blog\/free-email-or-custom-domain-email-which-one-is-better-for-cold-emailing\/\">aqu\u00ed<\/a>.<\/p>\n<p>Adem\u00e1s, tus destinatarios te tratar\u00e1n con m\u00e1s seriedad si reciben un correo electr\u00f3nico de una direcci\u00f3n que incluye un dominio empresarial, en lugar de name267@gmail.com. Por lo tanto, si decides utilizar una cuenta de Gmail gratuita para tus actividades de difusi\u00f3n, aseg\u00farate de que la direcci\u00f3n parezca segura y leg\u00edtima para tus destinatarios. Comprueba por qu\u00e9 la l\u00ednea del remitente <a href=\"https:\/\/woodpecker.co\/blog\/from-line\/\">es tan importante en la divulgaci\u00f3n por correo electr\u00f3nico en fr\u00edo.<\/a><\/p>\n<p>Sin embargo, lo m\u00e1s importante es tener en cuenta que el control de la cantidad de su alcance es una cosa, pero tambi\u00e9n hay que cuidar la calidad. Si env\u00edas correos electr\u00f3nicos fr\u00edos de baja calidad y sin personalizaci\u00f3n a un mont\u00f3n de direcciones no verificadas, tu proveedor puede bloquearte incluso antes de que alcances el l\u00edmite de cantidad. Especialmente si tu proveedor es Gmail. As\u00ed que ten en cuenta que la calidad es a\u00fan m\u00e1s importante que la cantidad en este sentido.<\/p>\n<p><strong>Recurso directo<\/strong>: <a href=\"https:\/\/support.google.com\/mail\/answer\/22839?hl=en\">L\u00edmites de env\u00edo y recepci\u00f3n de correo para las cuentas gratuitas de Gmail &gt;&gt;<\/a><\/p>\n<h2>L\u00edmite de env\u00edo de correo electr\u00f3nico de Google Workspace (antes G Suite)<\/h2>\n<p><strong>Por d\u00eda<\/strong>: 2000 mensajes (500 en prueba)<\/p>\n<p><strong>Por hora<\/strong>: Oficialmente, no hay l\u00edmites por hora<\/p>\n<p><strong>M\u00e1s informaci\u00f3n<\/strong>: Si superas los l\u00edmites, tu cuenta se bloquear\u00e1 hasta 24 horas.<\/p>\n<p>Al igual que en el caso de una cuenta gratuita de Gmail, la calidad de tus mensajes es tremendamente importante para la entregabilidad, y una mala entregabilidad puede hacer que tu cuenta se bloquee incluso antes de que alcances el l\u00edmite de cantidad. Por lo tanto, si te bloquean a pesar de enviar un n\u00famero limitado de mensajes, comprueba que el texto de tu correo electr\u00f3nico no contenga palabras de spam, enlaces rotos, tasa de conversi\u00f3n de html a texto y falta de personalizaci\u00f3n.<\/p>\n<p>Si los mecanismos antispam de Google encuentran algo que pueda sugerir que tus correos electr\u00f3nicos pueden ser spam, te bloquear\u00e1n. Esto tiene mucho sentido si lo piensas: una de las formas m\u00e1s efectivas de evitar que el spam llegue a las bandejas de entrada de la gente es evitar que la gente env\u00ede spam en primer lugar.<\/p>\n<p>Informaci\u00f3n importante sobre Google Workspace: Despu\u00e9s de actualizar tu cuenta en Google Workspace de la versi\u00f3n de prueba a la premium, no tendr\u00e1s autom\u00e1ticamente 2000 mensajes para enviar al d\u00eda. Tienes que esperar para aumentar tus l\u00edmites. Pero puedes aumentar los l\u00edmites antes. S\u00f3lo tienes que leer el recurso directo sobre c\u00f3mo hacerlo.<\/p>\n<p><strong>Recurso directo:<\/strong> <a href=\"https:\/\/support.google.com\/a\/answer\/166852?hl=en\">L\u00edmites de env\u00edo de Gmail en Google Workspace&gt;&gt;<\/a><\/p>\n<h2>L\u00edmite de env\u00edo de correo electr\u00f3nico de Office365<\/h2>\n<p><strong>Por d\u00eda<\/strong>: 10 000 destinatarios<\/p>\n<p><strong>Por hora:<\/strong> No hay l\u00edmite por hora, sino un l\u00edmite por minuto, que es de 30 mensajes como m\u00e1ximo<\/p>\n<p><strong>M\u00e1s informaci\u00f3n:<\/strong> Si te tomas en serio el alcance, ni siquiera te acercar\u00e1s al l\u00edmite diario de Office 365. 10.000 por d\u00eda suena rid\u00edculo para un alcance de correo electr\u00f3nico de calidad. Pero, ten en cuenta el l\u00edmite por minuto, especialmente si utilizas alguna automatizaci\u00f3n para enviar tus campa\u00f1as salientes.<\/p>\n<p>Usando Woodpecker, no te acercar\u00e1s ni siquiera al l\u00edmite por minuto de Office 365, ya que Woodpecker env\u00eda tus mensajes uno a uno, en momentos aleatorios, pero no con m\u00e1s frecuencia que cada 10-20 segundos. Lo que significa que no podr\u00e1s enviar m\u00e1s de 6 mensajes por minuto con Woodpecker.<\/p>\n<p>Al igual que en el caso de otros proveedores, una mala capacidad de entrega de sus correos electr\u00f3nicos puede hacer que se bloqueen antes de llegar a los correos de env\u00edo. En realidad, es m\u00e1s importante la cantidad de correos electr\u00f3nicos que env\u00edas que realmente llegan a las bandejas de entrada de tus clientes potenciales. Si el ratio de entrega\/env\u00edo es bajo, pareces un spammer y puedes ser bloqueado por ello. Para asegurarse de que su capacidad de entrega est\u00e1 en un nivel decente, lleve a cabo las <a href=\"https:\/\/woodpecker.co\/blog\/deliverability-checks\/\">14 comprobaciones de entregabilidad.<\/a><\/p>\n<p><strong>Recurso directo:<\/strong> <a href=\"https:\/\/docs.microsoft.com\/en-us\/office365\/servicedescriptions\/exchange-online-service-description\/exchange-online-limits?redirectedfrom=MSDN#RecipientLimits\">L\u00edmites de Exchange Online, Office 365: L\u00edmites de recepci\u00f3n y env\u00edo &gt;&gt;<\/a><\/p>\n<h2>L\u00edmite de env\u00edo de correo electr\u00f3nico de Outlook.com<\/h2>\n<p><strong>Por d\u00eda<\/strong>: 300 correos electr\u00f3nicos como m\u00e1ximo para direcciones de correo electr\u00f3nico de Outlook.com verificadas y con buena reputaci\u00f3n.<\/p>\n<p>\u00bfQu\u00e9 significa que una direcci\u00f3n de correo electr\u00f3nico de Outlook.com est\u00e1 verificada y tiene una buena reputaci\u00f3n? La reputaci\u00f3n de su direcci\u00f3n de correo electr\u00f3nico la determina Outlook.com en funci\u00f3n de factores como<\/p>\n<ul>\n<li>la antig\u00fcedad de su cuenta de correo electr\u00f3nico (si tiene menos de 30 d\u00edas, los l\u00edmites de env\u00edo de correo electr\u00f3nico son menores)<\/li>\n<li>la frecuencia con la que utilizas tu cuenta de outlook.com (cuanto m\u00e1s a menudo, mejor es tu reputaci\u00f3n)<\/li>\n<li>si tu cuenta de correo electr\u00f3nico est\u00e1 verificada (puedes verificarla en <a href=\"https:\/\/login.live.com\/login.srf?wa=wsignin1.0&amp;rpsnv=13&amp;ct=1594634773&amp;rver=7.3.6960.0&amp;wp=SAPI&amp;wreply=https%3A%2F%2Faccount.live.com%2Freputationcheck%3Fuaid%3D0eec39c24f3f4cc4b21292be1068dc75&amp;lc=1033&amp;id=38936&amp;mkt=pl-PL&amp;uaid=0eec39c24f3f4cc4b21292be1068dc75\">este enlace)<\/a>.<\/li>\n<\/ul>\n<p>\n<aside class=\"cta-block cta-block--a-version js-cta-block ab-no-10-cta-block ab-no-11-cta-block\">\n  <p class=\"cta-block__heading u-heading-preset-md-600\">Get more out of each email you send<\/p>\n  <div class=\"cta-block__form-container\">\n    <form class=\"js-cta-block-form\" action=\"https:\/\/woodpecker.co\/signup\/\" class=\"cta-block__button-only-form js-cta-block-no-input-form\">\n      \n\n\n\n\n\n\n\n\n<button class=\"c-button js-button c-button--color-main c-button--size-small u-focus-visible-outline\">\nIniciar prueba gratuita\n<\/button>    <\/form>\n    \n    <form class=\"c-input-button-form js-cta-block-form cta-block__form\" action=\"https:\/\/woodpecker.co\/signup\/\" method=\"POST\" novalidate>\n        \n  <div class=\"c-form-field js-form-field  c-input-button-form__form-field\">\n    \n    <label class=\"c-label c-form-field__label\" for=\"cta-block-form-email-2003033065\">Work email<\/label>\n\n                    \n  <input class=\"c-input  js-input c-input-button-form__input\" placeholder=\"will@woodpecker.co\" name=\"email\" id=\"cta-block-form-email-2003033065\" type=\"email\" \/>\n            \n    <span class=\"c-form-field__error js-error\">\n                                      Invalid email format\n        \n\n                <\/span>\n  <\/div>\n\n        <div class=\"c-input-button-form__button\">\n          \n\n\n\n\n\n\n\n\n<button class=\"cta-block__button c-button js-button c-button--color-main c-button--size-small u-focus-visible-outline\">\n                Iniciar prueba gratuita\n        \n\n<\/button>        <\/div>\n\n            <\/form>\n  <\/div>\n<\/aside><\/p>\n<h2>L\u00edmite de env\u00edo de correo electr\u00f3nico de GoDaddy (cuentas de correo electr\u00f3nico de Workspace)<\/h2>\n<p><strong>Por d\u00eda:<\/strong> 250 destinatarios, pero puedes aumentar el l\u00edmite hasta 500 por un coste adicional<\/p>\n<p><strong>Por hora:<\/strong> m\u00e1x. 300 mensajes por hora; m\u00e1x. 200 mensajes por minuto<\/p>\n<p><strong>M\u00e1s informaci\u00f3n:<\/strong> Es bastante f\u00e1cil llegar al l\u00edmite de destinatarios diarios si env\u00edas unas cuantas campa\u00f1as con seguimiento utilizando la automatizaci\u00f3n. As\u00ed que si env\u00edas varias campa\u00f1as con seguimiento, aseg\u00farate de programar los mensajes dentro de todas tus campa\u00f1as para varios d\u00edas de la semana. O utiliza m\u00e1s de una direcci\u00f3n de correo electr\u00f3nico para asegurarte de que tus mensajes de primer contacto y de seguimiento no se solapen de forma que te bloqueen el env\u00edo.<\/p>\n<p>En cuanto al l\u00edmite por minuto, con Woodpecker est\u00e1s totalmente a salvo de sobrepasarlo, ya que no podr\u00e1s enviar m\u00e1s de 6 correos electr\u00f3nicos por minuto, aunque te esforzaras en enviar m\u00e1s. Eso s\u00ed, s\u00e9 inteligente a la hora de establecer las horas de entrega de tus mensajes. Si estableces una ventana de una hora y decides enviar tu campa\u00f1a a m\u00e1s de 300 prospectos, te estar\u00e1s acercando peligrosamente al l\u00edmite horario de GoDaddy.<\/p>\n<p><strong>Recurso directo:<\/strong> <a href=\"https:\/\/pl.godaddy.com\/help\/ograniczenia-konta-workspace-email-2949\">Limitaciones de la cuenta de correo electr\u00f3nico de GoDaddy Workspace &gt;&gt;<\/a><\/p>\n<h2>BTW, cuidado con los picos de actividad en tu buz\u00f3n de correo<\/h2>\n<p>Siempre es una buena idea establecer per\u00edodos m\u00e1s largos para enviar un mensaje a un grupo m\u00e1s grande de prospectos, porque entonces los mensajes particulares se env\u00edan con menos frecuencia, y no hay picos en la actividad de su cuenta <a href=\"https:\/\/woodpecker.co\/blog\/mailbox-for-outbound\/\">de correo electr\u00f3nico<\/a>. Si tienes una cuenta de correo electr\u00f3nico dedicada a la difusi\u00f3n, y apenas env\u00edas nada desde esta cuenta a diario, pero de repente intentas enviar 300 correos electr\u00f3nicos durante una hora, esto parece sospechoso para cualquier proveedor de correo electr\u00f3nico. La clave es organizar tu alcance de manera que permita un flujo fluido y constante de mensajes salientes.<\/p>\n<p>Apuesto a que alguien te ha dicho al menos una vez en tu vida que hay unas &#8220;<a href=\"https:\/\/woodpecker.co\/blog\/optimal-time-for-cold-email-delivery-vol-1-stats\/\">horas de oro&#8221; para el env\u00edo de correos electr\u00f3nicos<\/a> (seguro que conoces el consejo de &#8220;no env\u00edes los lunes, env\u00eda los martes antes de comer&#8221;). As\u00ed que puede que tengas la tentaci\u00f3n de programar todas tus campa\u00f1as para que se env\u00eden los martes entre las 10 y las 11 de la ma\u00f1ana. Pues bien, \u00a1prep\u00e1rate y resiste esta tentaci\u00f3n! Esto no es un bolet\u00edn de noticias, es un correo electr\u00f3nico fr\u00edo (comprueba la diferencia aqu\u00ed).<\/p>\n<p>Y creo que no existen las &#8220;horas de oro&#8221; universales para enviar correos electr\u00f3nicos. Tienes que descubrir las &#8220;horas de oro&#8221; para tu grupo espec\u00edfico de clientes potenciales. Y si env\u00edas de forma autom\u00e1tica, dale a tus emails m\u00e1s tiempo que una hora para que se env\u00eden de forma m\u00e1s natural y as\u00ed evitar que te bloqueen por un pico alarmante y poco natural en la actividad de tu buz\u00f3n.<\/p>\n<p>Bien, volvamos a los l\u00edmites de env\u00edo.<\/p>\n<h2>L\u00edmites de env\u00edo de correo electr\u00f3nico de Rackspace<\/h2>\n<p><strong>Por d\u00eda:<\/strong> 10 000 destinatarios<\/p>\n<p><strong>Por hora:<\/strong> No hay informaci\u00f3n oficial sobre un l\u00edmite por hora<\/p>\n<p><strong>Informaci\u00f3n adicional:<\/strong> Seg\u00fan nuestra experiencia, Rackspace presta m\u00e1s atenci\u00f3n a la calidad de sus mensajes que a la cantidad de los mismos. No se deje enga\u00f1ar f\u00e1cilmente por el l\u00edmite de 10K diarios. Si env\u00eda mensajes de baja calidad a trav\u00e9s de Rackspace, se bloquear\u00e1 mucho antes.<\/p>\n<p>Recuerde que es muy importante saber cu\u00e1ntos de sus correos electr\u00f3nicos llegan realmente a su destino. Si se clasifican como spam, ya sea por los filtros anti-spam, o lo que es peor, por sus clientes potenciales, usted puede ser bloqueado despu\u00e9s de s\u00f3lo unas horas de presionar &#8220;enviar&#8221;.<\/p>\n<p><strong>Recursos directos:<\/strong><\/p>\n<ul>\n<li><a href=\"https:\/\/docs.rackspace.com\/support\/how-to\/rackspace-hosted-email-system-daily-sending-limit\/\">L\u00edmite de env\u00edo diario para los sistemas de correo electr\u00f3nico alojados en Rackspace &gt;&gt;<\/a><\/li>\n<li><a href=\"https:\/\/www.rackspace.com\/information\/legal\/global\/aup\">Pol\u00edtica global de uso aceptable de Rackspace &gt;&gt;<\/a><\/li>\n<\/ul>\n<h2>L\u00edmite de env\u00edo de correo electr\u00f3nico de BlueHost<\/h2>\n<p><strong>Por d\u00eda<\/strong>: No he podido encontrar informaci\u00f3n directa sobre el l\u00edmite de env\u00edo diario de BlueHost.<\/p>\n<p><strong>Por hora<\/strong>: BlueHost permite enviar un m\u00e1ximo de 150 correos electr\u00f3nicos por hora con una frecuencia de 70 correos electr\u00f3nicos cada 30 minutos.<\/p>\n<p><strong>Informaci\u00f3n adicional<\/strong>: BlueHost dice que puedes aumentar el l\u00edmite por hora una vez que tengas una raz\u00f3n v\u00e1lida para hacerlo. S\u00f3lo tienes que ponerte en contacto con su equipo de soporte.<\/p>\n<p>Despu\u00e9s de experimentar el rebote de correo electr\u00f3nico, obtendr\u00e1 una advertencia o un error de tiempo de espera. BlueHost desactivar\u00e1 tu cuenta hasta que sea revisada. Una vez que la cuenta sea revisada, se activar\u00e1 en un lapso de 24 horas.<\/p>\n<p><strong>Recursos directos:<\/strong><\/p>\n<ul>\n<li><a href=\"https:\/\/www.bluehost.com\/help\/article\/email-deliverability-problems\">Problemas de entrega de correo electr\u00f3nico &gt;&gt;<\/a><\/li>\n<li><a href=\"https:\/\/www.bluehost.com\/help\/article\/email-returned-error-speed-limit-exceeded#vote\">Error de devoluci\u00f3n de correo electr\u00f3nico &#8211; l\u00edmite de velocidad excedido &gt;&gt;<\/a><\/li>\n<\/ul>\n<h2>L\u00edmite de env\u00edo de correo electr\u00f3nico de DreamHost<\/h2>\n<p><strong>Por hora:<\/strong> 100 destinatarios por hora cuando se trata de enviar un solo mensaje<\/p>\n<p><strong>Otros datos a tener en cuenta:<\/strong> Para enviar 5 mensajes diferentes a 5 destinatarios, la frecuencia de env\u00edo no es superior a 25 correos electr\u00f3nicos cada 15 minutos. Para enviar un solo correo electr\u00f3nico a muchos destinatarios, puede utilizar <a href=\"https:\/\/help.dreamhost.com\/hc\/en-us\/articles\/215683497-How-do-I-configure-and-manage-an-Announcement-List-\">una lista de anuncios configurada.<\/a><\/p>\n<p><strong>Recursos directos:<\/strong> <a href=\"https:\/\/help.dreamhost.com\/hc\/en-us\/articles\/215730437-SMTP-quota-limits\">L\u00edmites de cuota SMTP &gt;&gt;<\/a><\/p>\n<h2>L\u00edmite de env\u00edo de correos electr\u00f3nicos de Yahoo! Mail Plus<\/h2>\n<p><strong>Por d\u00eda:<\/strong> un m\u00e1ximo de 500 correos electr\u00f3nicos al d\u00eda. Cada correo electr\u00f3nico puede ser enviado a un m\u00e1ximo de 100 destinatarios. Cada destinatario de correo electr\u00f3nico cuenta como un correo electr\u00f3nico para el l\u00edmite diario de 500.<\/p>\n<p><strong>Por hora:<\/strong> No hay informaci\u00f3n oficial sobre el l\u00edmite por hora, pero algunas fuentes afirman que es de 100 correos electr\u00f3nicos\/hora<\/p>\n<p><strong>Recursos directos:<\/strong><\/p>\n<ul>\n<li><a href=\"https:\/\/consent.yahoo.com\/v2\/collectConsent?sessionId=3_cc-session_fc98dcbc-0ddc-40fe-b403-3d0c6b7b9c3d\">Preguntas frecuentes sobre la entregabilidad de Yahoo Mail &gt;&gt;<\/a><\/li>\n<li><a href=\"https:\/\/help.verizonsmallbusinessessentials.com\/s\/article\/SLN17518\">L\u00edmites de env\u00edo SMTP&gt;&gt;<\/a><\/li>\n<\/ul>\n<h2>L\u00edmite de env\u00edo de correo electr\u00f3nico de Yandex.mail<\/h2>\n<p><strong>Por d\u00eda:<\/strong> 500 correos electr\u00f3nicos (si el correo electr\u00f3nico tiene varios destinatarios, cada correo electr\u00f3nico enviado cuenta por separado para el total).<\/p>\n<p><strong>Recursos directos:<\/strong> <a href=\"https:\/\/yandex.com\/support\/mail\/web\/letter\/create\/send-many-letters.html\">Ayuda de Yandex.mail &gt;&gt;<\/a><\/p>\n<h2>L\u00edmite de env\u00edo de emails de Host Gator<\/h2>\n<p><strong>Por d\u00eda:<\/strong> 12,000<\/p>\n<p><strong>Por hora:<\/strong> 500 emails por dominio &#8211; cada subdominio tiene su propio l\u00edmite de 500 emails\/hora<\/p>\n<p><strong>M\u00e1s informaci\u00f3n:<\/strong> Una lista de correo que contenga m\u00e1s de 900 direcciones s\u00f3lo puede ser enviada durante<a href=\"https:\/\/www.hostgator.com\/help\/article\/mail-policy-and-limits\"> las horas de menor actividad<\/a>. Una lista de correo de m\u00e1s de 5.000 direcciones requiere un servidor dedicado o una soluci\u00f3n de alojamiento VPS de Host Gator. Dividir la lista en otras m\u00e1s peque\u00f1as no est\u00e1 permitido. Sin embargo, estos l\u00edmites no deben preocuparle, ya que el env\u00edo de tal cantidad de correos electr\u00f3nicos va en contra de la idea misma del cold emailing. \u00a1La calidad por encima de la cantidad!<\/p>\n<p><strong>Recursos directos:<\/strong> <a href=\"https:\/\/www.hostgator.com\/help\/article\/mail-policy-and-limits\">Pol\u00edtica de correo y l\u00edmites&gt;&gt;<\/a><\/p>\n<h2>En definitiva<\/h2>\n<p>Independientemente del proveedor de correo electr\u00f3nico que elijas, todos ellos prestan atenci\u00f3n no s\u00f3lo a lo que sale de tu buz\u00f3n, sino tambi\u00e9n a cu\u00e1ntos de los mensajes salientes llegan realmente a tus destinatarios. Por eso es tan importante cuidar la entregabilidad de tus correos electr\u00f3nicos.<\/p>\n<p>Por eso es bueno consultar:<\/p>\n<ul>\n<li><a href=\"https:\/\/woodpecker.co\/blog\/boost-cold-email-deliverability\/\">\u00bfQu\u00e9 podemos hacer para aumentar la entregabilidad de nuestros correos electr\u00f3nicos en fr\u00edo? &gt;&gt;<\/a><\/li>\n<li><a href=\"https:\/\/woodpecker.co\/blog\/deliverability-checks\/\">14 comprobaciones de entregabilidad que debe realizar antes de enviar su campa\u00f1a de correo electr\u00f3nico en fr\u00edo&gt;<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Tienes que saber esto. Especialmente si haces difusi\u00f3n por correo electr\u00f3nico. Cada proveedor de servicios de correo electr\u00f3nico tiene sus propios l\u00edmites de env\u00edo. Los l\u00edmites pueden ser diarios, por hora, y a veces tambi\u00e9n por minuto. Si est\u00e1 enviando campa\u00f1as de correo electr\u00f3nico en fr\u00edo sin ser consciente de los l\u00edmites de su proveedor de correo electr\u00f3nico, su cuenta de correo electr\u00f3nico puede ser bloqueada antes de que se d\u00e9 cuenta.<\/p>\n","protected":false},"author":2,"featured_media":14007,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[60],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfCu\u00e1les son los l\u00edmites de env\u00edo de correo electr\u00f3nico de los distintos hosts de correo electr\u00f3nico?<\/title>\n<meta name=\"description\" content=\"Aqu\u00ed est\u00e1 la informaci\u00f3n sobre los l\u00edmites de env\u00edo de correo electr\u00f3nico de los proveedores de servicios de correo electr\u00f3nico m\u00e1s populares, incluyendo Gmail, Office 365, GoDaddy y m\u00e1s.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/woodpecker.co\/blog\/es\/cuales-son-los-limites-de-envio-de-correo-electronico-de-los-distintos-proveedores-de-servicios-de-correo-electronico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfCu\u00e1les son los l\u00edmites de env\u00edo de correo electr\u00f3nico de los distintos hosts de correo electr\u00f3nico?\" \/>\n<meta property=\"og:description\" content=\"Aqu\u00ed est\u00e1 la informaci\u00f3n sobre los l\u00edmites de env\u00edo de correo electr\u00f3nico de los proveedores de servicios de correo electr\u00f3nico m\u00e1s populares, incluyendo Gmail, Office 365, GoDaddy y m\u00e1s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/woodpecker.co\/blog\/es\/cuales-son-los-limites-de-envio-de-correo-electronico-de-los-distintos-proveedores-de-servicios-de-correo-electronico\/\" \/>\n<meta property=\"og:site_name\" content=\"Woodpecker Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/business.facebook.com\/woodpeckerapp\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-11T09:06:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-11T09:47:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/woodpecker.co\/blog\/app\/uploads\/2020\/12\/What_Are_Email_Sending_Limits_of_Various_Email_Service_Providers1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"650\" \/>\n\t<meta property=\"og:image:height\" content=\"391\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Cathy Dawiskiba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/kapatalas\" \/>\n<meta name=\"twitter:site\" content=\"@woodpeckerapp\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/woodpecker.co\/blog\/es\/cuales-son-los-limites-de-envio-de-correo-electronico-de-los-distintos-proveedores-de-servicios-de-correo-electronico\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/woodpecker.co\/blog\/es\/cuales-son-los-limites-de-envio-de-correo-electronico-de-los-distintos-proveedores-de-servicios-de-correo-electronico\/\"},\"author\":{\"name\":\"Cathy Dawiskiba\",\"@id\":\"https:\/\/woodpecker.co\/blog\/#\/schema\/person\/ef0d7f439f5185f3655b45d8ad3462fd\"},\"headline\":\"\u00bfCu\u00e1les son los l\u00edmites de env\u00edo de correo electr\u00f3nico de los distintos proveedores de servicios de correo electr\u00f3nico?\",\"datePublished\":\"2022-04-11T09:06:51+00:00\",\"dateModified\":\"2022-04-11T09:47:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/woodpecker.co\/blog\/es\/cuales-son-los-limites-de-envio-de-correo-electronico-de-los-distintos-proveedores-de-servicios-de-correo-electronico\/\"},\"wordCount\":3140,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/woodpecker.co\/blog\/#organization\"},\"articleSection\":[\"Deliverability\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/woodpecker.co\/blog\/es\/cuales-son-los-limites-de-envio-de-correo-electronico-de-los-distintos-proveedores-de-servicios-de-correo-electronico\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/woodpecker.co\/blog\/es\/cuales-son-los-limites-de-envio-de-correo-electronico-de-los-distintos-proveedores-de-servicios-de-correo-electronico\/\",\"url\":\"https:\/\/woodpecker.co\/blog\/es\/cuales-son-los-limites-de-envio-de-correo-electronico-de-los-distintos-proveedores-de-servicios-de-correo-electronico\/\",\"name\":\"\u00bfCu\u00e1les son los l\u00edmites de env\u00edo de correo electr\u00f3nico de los distintos hosts de correo electr\u00f3nico?\",\"isPartOf\":{\"@id\":\"https:\/\/woodpecker.co\/blog\/#website\"},\"datePublished\":\"2022-04-11T09:06:51+00:00\",\"dateModified\":\"2022-04-11T09:47:08+00:00\",\"description\":\"Aqu\u00ed est\u00e1 la informaci\u00f3n sobre los l\u00edmites de env\u00edo de correo electr\u00f3nico de los proveedores de servicios de correo electr\u00f3nico m\u00e1s populares, incluyendo Gmail, Office 365, GoDaddy y m\u00e1s.\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/woodpecker.co\/blog\/es\/cuales-son-los-limites-de-envio-de-correo-electronico-de-los-distintos-proveedores-de-servicios-de-correo-electronico\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/woodpecker.co\/blog\/#website\",\"url\":\"https:\/\/woodpecker.co\/blog\/\",\"name\":\"Woodpecker Blog\",\"description\":\"Woodpecker Blog - Pro Tips on Cold Emails, Follow-ups, Sales &amp; Growth\",\"publisher\":{\"@id\":\"https:\/\/woodpecker.co\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/woodpecker.co\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/woodpecker.co\/blog\/#organization\",\"name\":\"Woodpecker.co\",\"url\":\"https:\/\/woodpecker.co\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/woodpecker.co\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/woodpecker.co\/blog\/app\/uploads\/2015\/06\/WP_Logo_WersjaPodstawowa_Pionowa_CzarneTlo_RGB.jpg\",\"contentUrl\":\"https:\/\/woodpecker.co\/blog\/app\/uploads\/2015\/06\/WP_Logo_WersjaPodstawowa_Pionowa_CzarneTlo_RGB.jpg\",\"width\":1240,\"height\":874,\"caption\":\"Woodpecker.co\"},\"image\":{\"@id\":\"https:\/\/woodpecker.co\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/business.facebook.com\/woodpeckerapp\",\"https:\/\/twitter.com\/woodpeckerapp\",\"https:\/\/www.instagram.com\/woodpeckerapp\/\",\"https:\/\/www.linkedin.com\/company\/woodpecker-co\/\",\"https:\/\/www.youtube.com\/channel\/UCNN9wM55yaNI-KEZCfh66_A\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/woodpecker.co\/blog\/#\/schema\/person\/ef0d7f439f5185f3655b45d8ad3462fd\",\"name\":\"Cathy Dawiskiba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/woodpecker.co\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5c879fd5792a7f64321f42046c8789dc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5c879fd5792a7f64321f42046c8789dc?s=96&d=mm&r=g\",\"caption\":\"Cathy Dawiskiba\"},\"description\":\"Cathy started this blog a long time ago, though it seems like it was yesterday.\",\"sameAs\":[\"https:\/\/linkedin.com\/in\/kapatalas\",\"https:\/\/twitter.com\/https:\/\/twitter.com\/kapatalas\"],\"url\":\"https:\/\/woodpecker.co\/blog\/es\/author\/cathy\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfCu\u00e1les son los l\u00edmites de env\u00edo de correo electr\u00f3nico de los distintos hosts de correo electr\u00f3nico?","description":"Aqu\u00ed est\u00e1 la informaci\u00f3n sobre los l\u00edmites de env\u00edo de correo electr\u00f3nico de los proveedores de servicios de correo electr\u00f3nico m\u00e1s populares, incluyendo Gmail, Office 365, GoDaddy y m\u00e1s.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/woodpecker.co\/blog\/es\/cuales-son-los-limites-de-envio-de-correo-electronico-de-los-distintos-proveedores-de-servicios-de-correo-electronico\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfCu\u00e1les son los l\u00edmites de env\u00edo de correo electr\u00f3nico de los distintos hosts de correo electr\u00f3nico?","og_description":"Aqu\u00ed est\u00e1 la informaci\u00f3n sobre los l\u00edmites de env\u00edo de correo electr\u00f3nico de los proveedores de servicios de correo electr\u00f3nico m\u00e1s populares, incluyendo Gmail, Office 365, GoDaddy y m\u00e1s.","og_url":"https:\/\/woodpecker.co\/blog\/es\/cuales-son-los-limites-de-envio-de-correo-electronico-de-los-distintos-proveedores-de-servicios-de-correo-electronico\/","og_site_name":"Woodpecker Blog","article_publisher":"https:\/\/business.facebook.com\/woodpeckerapp","article_published_time":"2022-04-11T09:06:51+00:00","article_modified_time":"2022-04-11T09:47:08+00:00","og_image":[{"width":650,"height":391,"url":"https:\/\/woodpecker.co\/blog\/app\/uploads\/2020\/12\/What_Are_Email_Sending_Limits_of_Various_Email_Service_Providers1.png","type":"image\/png"}],"author":"Cathy Dawiskiba","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/kapatalas","twitter_site":"@woodpeckerapp","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/woodpecker.co\/blog\/es\/cuales-son-los-limites-de-envio-de-correo-electronico-de-los-distintos-proveedores-de-servicios-de-correo-electronico\/#article","isPartOf":{"@id":"https:\/\/woodpecker.co\/blog\/es\/cuales-son-los-limites-de-envio-de-correo-electronico-de-los-distintos-proveedores-de-servicios-de-correo-electronico\/"},"author":{"name":"Cathy Dawiskiba","@id":"https:\/\/woodpecker.co\/blog\/#\/schema\/person\/ef0d7f439f5185f3655b45d8ad3462fd"},"headline":"\u00bfCu\u00e1les son los l\u00edmites de env\u00edo de correo electr\u00f3nico de los distintos proveedores de servicios de correo electr\u00f3nico?","datePublished":"2022-04-11T09:06:51+00:00","dateModified":"2022-04-11T09:47:08+00:00","mainEntityOfPage":{"@id":"https:\/\/woodpecker.co\/blog\/es\/cuales-son-los-limites-de-envio-de-correo-electronico-de-los-distintos-proveedores-de-servicios-de-correo-electronico\/"},"wordCount":3140,"commentCount":0,"publisher":{"@id":"https:\/\/woodpecker.co\/blog\/#organization"},"articleSection":["Deliverability"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/woodpecker.co\/blog\/es\/cuales-son-los-limites-de-envio-de-correo-electronico-de-los-distintos-proveedores-de-servicios-de-correo-electronico\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/woodpecker.co\/blog\/es\/cuales-son-los-limites-de-envio-de-correo-electronico-de-los-distintos-proveedores-de-servicios-de-correo-electronico\/","url":"https:\/\/woodpecker.co\/blog\/es\/cuales-son-los-limites-de-envio-de-correo-electronico-de-los-distintos-proveedores-de-servicios-de-correo-electronico\/","name":"\u00bfCu\u00e1les son los l\u00edmites de env\u00edo de correo electr\u00f3nico de los distintos hosts de correo electr\u00f3nico?","isPartOf":{"@id":"https:\/\/woodpecker.co\/blog\/#website"},"datePublished":"2022-04-11T09:06:51+00:00","dateModified":"2022-04-11T09:47:08+00:00","description":"Aqu\u00ed est\u00e1 la informaci\u00f3n sobre los l\u00edmites de env\u00edo de correo electr\u00f3nico de los proveedores de servicios de correo electr\u00f3nico m\u00e1s populares, incluyendo Gmail, Office 365, GoDaddy y m\u00e1s.","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/woodpecker.co\/blog\/es\/cuales-son-los-limites-de-envio-de-correo-electronico-de-los-distintos-proveedores-de-servicios-de-correo-electronico\/"]}]},{"@type":"WebSite","@id":"https:\/\/woodpecker.co\/blog\/#website","url":"https:\/\/woodpecker.co\/blog\/","name":"Woodpecker Blog","description":"Woodpecker Blog - Pro Tips on Cold Emails, Follow-ups, Sales &amp; Growth","publisher":{"@id":"https:\/\/woodpecker.co\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/woodpecker.co\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/woodpecker.co\/blog\/#organization","name":"Woodpecker.co","url":"https:\/\/woodpecker.co\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/woodpecker.co\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/woodpecker.co\/blog\/app\/uploads\/2015\/06\/WP_Logo_WersjaPodstawowa_Pionowa_CzarneTlo_RGB.jpg","contentUrl":"https:\/\/woodpecker.co\/blog\/app\/uploads\/2015\/06\/WP_Logo_WersjaPodstawowa_Pionowa_CzarneTlo_RGB.jpg","width":1240,"height":874,"caption":"Woodpecker.co"},"image":{"@id":"https:\/\/woodpecker.co\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/business.facebook.com\/woodpeckerapp","https:\/\/twitter.com\/woodpeckerapp","https:\/\/www.instagram.com\/woodpeckerapp\/","https:\/\/www.linkedin.com\/company\/woodpecker-co\/","https:\/\/www.youtube.com\/channel\/UCNN9wM55yaNI-KEZCfh66_A"]},{"@type":"Person","@id":"https:\/\/woodpecker.co\/blog\/#\/schema\/person\/ef0d7f439f5185f3655b45d8ad3462fd","name":"Cathy Dawiskiba","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/woodpecker.co\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5c879fd5792a7f64321f42046c8789dc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5c879fd5792a7f64321f42046c8789dc?s=96&d=mm&r=g","caption":"Cathy Dawiskiba"},"description":"Cathy started this blog a long time ago, though it seems like it was yesterday.","sameAs":["https:\/\/linkedin.com\/in\/kapatalas","https:\/\/twitter.com\/https:\/\/twitter.com\/kapatalas"],"url":"https:\/\/woodpecker.co\/blog\/es\/author\/cathy\/"}]}},"_links":{"self":[{"href":"https:\/\/woodpecker.co\/blog\/es\/wp-json\/wp\/v2\/posts\/14006"}],"collection":[{"href":"https:\/\/woodpecker.co\/blog\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/woodpecker.co\/blog\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/woodpecker.co\/blog\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/woodpecker.co\/blog\/es\/wp-json\/wp\/v2\/comments?post=14006"}],"version-history":[{"count":3,"href":"https:\/\/woodpecker.co\/blog\/es\/wp-json\/wp\/v2\/posts\/14006\/revisions"}],"predecessor-version":[{"id":14017,"href":"https:\/\/woodpecker.co\/blog\/es\/wp-json\/wp\/v2\/posts\/14006\/revisions\/14017"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/woodpecker.co\/blog\/es\/wp-json\/wp\/v2\/media\/14007"}],"wp:attachment":[{"href":"https:\/\/woodpecker.co\/blog\/es\/wp-json\/wp\/v2\/media?parent=14006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/woodpecker.co\/blog\/es\/wp-json\/wp\/v2\/categories?post=14006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/woodpecker.co\/blog\/es\/wp-json\/wp\/v2\/tags?post=14006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}