{"id":22526,"date":"2023-08-23T12:16:49","date_gmt":"2023-08-23T11:16:49","guid":{"rendered":"https:\/\/woodpecker.co\/blog\/?p=22526"},"modified":"2023-08-23T12:16:49","modified_gmt":"2023-08-23T11:16:49","slug":"von-schrecklichen-kalt-e-mails-zu-gewinnenden-kalt-e-mails-zwei-beispiele-aus-der-praxis","status":"publish","type":"post","link":"https:\/\/woodpecker.co\/blog\/de\/von-schrecklichen-kalt-e-mails-zu-gewinnenden-kalt-e-mails-zwei-beispiele-aus-der-praxis\/","title":{"rendered":"Von schrecklichen Kalt-E-Mails zu gewinnenden Kalt-E-Mails: Zwei Beispiele aus der Praxis"},"content":{"rendered":"<p><span style=\"font-weight: 400;\"><a href=\"https:\/\/woodpecker.co\/blog\/how-to-write-a-cold-email-that-actually-works-six-step-tutorial\/\">Eine gute Kaltakquise-E-Mail zu schreiben<\/a> ist schwieriger als es scheint.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">In diesem Blogbeitrag zeigen wir Ihnen Beispiele f\u00fcr gute und schlechte E-Mails aus der Praxis. Lassen Sie sich von ihnen inspirieren, wenn Sie Ihre eigenen erstellen wollen.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ich habe die Expertin f\u00fcr Kaltakquise und unsere Partnerin <a href=\"https:\/\/www.lauralopuch.com\">Laura Lopuch<\/a> gebeten, sich zu diesem Thema zu \u00e4u\u00dfern und zu zeigen, wie sie vom Schreiben schrecklicher Kaltakquise-E-Mails zu erfolgreichen E-Mails gekommen ist.<\/span><\/p>\n<p>\u00dcbernehmen Sie, Laura.<\/p>\n<p style=\"text-align: center;\">***<\/p>\n<p>Als ich anfing, Kaltakquise-E-Mails zu schreiben, h\u00e4tte ich eine schlechte E-Mail nicht einmal erkannt, wenn sie mir wie ein sterbender Fisch vor die F\u00fc\u00dfe gefallen w\u00e4re.<\/p>\n<p>Stattdessen h\u00e4tte ich sie nur verwundert angeschaut und gesagt: &#8220;Hm, sieht aus wie eine E-Mail. Ich frage mich, warum sie stirbt?&#8221;<\/p>\n<p>Und das, mein Freund, ist der Grund, warum die ersten drei Monate meiner Kaltakquise ein Tornado aus wirbelnden Selbstzweifeln und Frustration waren.<\/p>\n<p>Treu und brav verschickte ich jede Woche 25 neue Kaltakquise-E-Mails, um neue Kunden zu gewinnen. Ich optimierte und \u00fcberarbeitete meine Kaltakquise-E-Mails und ertrug die nicht enden wollende Stille.<\/p>\n<p>Es f\u00fchlte sich an, als w\u00fcrde ich eine E-Mail an den M\u00fclleimer des Internets schicken.<\/p>\n<p>Warum konnte ich keine Antwort erhalten?<\/p>\n<p>War mit meinem Angebot etwas nicht in Ordnung?<\/p>\n<p>Oder schlimmer noch: stimmte etwas mit mir nicht?<\/p>\n<p>Das Internet ist \u00fcberschwemmt mit Beispielen f\u00fcr Kaltakquise-E-Mails, die alle behaupten, sie seien &#8220;gro\u00dfartige Kaltakquise-E-Mails&#8221;. Und das ist schlecht so.<\/p>\n<p>Denn: Woher soll man wissen, was eine schlechte Kaltakquise-E-Mail ist, wenn niemand eine im Vergleich zu einer guten Kaltakquise-E-Mail zeigt?<\/p>\n<p>Und wenn Sie nicht wissen, wie eine schlechte E-Mail aussieht, wie k\u00f6nnen Sie dann Ihre <a href=\"https:\/\/woodpecker.co\/blog\/how-to-write-a-cold-email-that-actually-works-six-step-tutorial\/\">Cold E-Mail<\/a> zu einer erfolgreichen E-Mail machen?<\/p>\n<p>Heute werden wir das \u00e4ndern.<\/p>\n<p>\n<aside class=\"cta-block cta-block--a-version js-cta-block ab-no-10-cta-block ab-no-11-cta-block\">\n  <p class=\"cta-block__heading u-heading-preset-md-600\">Senden Sie aussagekr\u00e4ftige E-Mails und steigern Sie die Anzahl der Antworten<\/p>\n  <div class=\"cta-block__form-container\">\n    <form class=\"js-cta-block-form\" action=\"\" class=\"cta-block__button-only-form js-cta-block-no-input-form\">\n      \n\n\n\n\n\n\n\n\n<button class=\"c-button js-button c-button--color-main c-button--size-small u-focus-visible-outline\">\nKostenlose Testversion starten\n<\/button>    <\/form>\n    \n    <form class=\"c-input-button-form js-cta-block-form cta-block__form\" method=\"POST\" novalidate>\n        \n  <div class=\"c-form-field js-form-field  c-input-button-form__form-field\">\n    \n    <label class=\"c-label c-form-field__label\" for=\"cta-block-form-email-466161418\">Work email<\/label>\n\n                    \n  <input class=\"c-input  js-input c-input-button-form__input\" placeholder=\"will@woodpecker.co\" name=\"email\" id=\"cta-block-form-email-466161418\" type=\"email\" \/>\n            \n    <span class=\"c-form-field__error js-error\">\n                                      Invalid email format\n        \n\n                <\/span>\n  <\/div>\n\n        <div class=\"c-input-button-form__button\">\n          \n\n\n\n\n\n\n\n\n<button class=\"cta-block__button c-button js-button c-button--color-main c-button--size-small u-focus-visible-outline\">\n                Kostenlose Testversion starten\n        \n\n<\/button>        <\/div>\n\n            <\/form>\n  <\/div>\n<\/aside><br \/>\n<aside class=\"cta-ebook-bundle js-cta-ebook-bundle ab-no-11-cta-ebook-bundle\">\n\t<div class=\"cta-ebook-bundle__container\">\n\t\t<div class=\"cta-ebook-bundle__content\">\n\t\t\t<div class=\"u-heading-preset-md-600\">\n\t\t\t\tSign up now and get our exclusive 3-ebook pack\n\t\t\t<\/div>\n\n\t\t\t<div class=\"cta-ebook-bundle__subheading u-heading-sm-400 u-text-l-400@mobile\">\n\t\t\t\t<span class=\"u-text-bg cta-ebook-bundle__accent\">Beginners Bundle<\/span> for free!\n\t\t\t<\/div>\n\n\t\t\t<img src=\"https:\/\/woodpecker.co\/blog\/app\/themes\/woodpecker-blog\/assets\/img\/cta-ebook-bundle-drawing.svg\" alt=\"\" class=\"cta-ebook-bundle__image\">\n\n\t\t\t\n    <form class=\"c-input-button-form js-cta-ebook-bundle-form\" action=\"https:\/\/woodpecker.co\/signup\/?variant=ebook-bundle\" method=\"POST\" novalidate>\n        \n  <div class=\"c-form-field js-form-field  c-input-button-form__form-field\">\n    \n    <label class=\"c-label c-form-field__label\">Work email<\/label>\n\n                    \n  <input class=\"c-input  js-input c-input-button-form__input\" placeholder=\"will@woodpecker.co\" name=\"email\" type=\"email\" \/>\n            \n    <span class=\"c-form-field__error js-error\">\n                          \t\t\t\t\tInvalid email format\n\t\t\t\t\n\n                <\/span>\n  <\/div>\n\n        <div class=\"c-input-button-form__button\">\n          \n\n\n\n\n\n\n\n\n<button class=\" c-button js-button c-button--color-main c-button--size-small u-focus-visible-outline\">\n    \t\t\t\t\tGet free TRIAL & ebook pack\n\t\t\t\t\n\n<\/button>        <\/div>\n\n            <\/form>\n\t\t<\/div>\n\t<\/div>\n<\/aside>\n<\/p>\n<p>In diesem Beitrag werde ich zwei Teardowns durchf\u00fchren:<\/p>\n<ol>\n<li>Eine schreckliche Kaltakquise-E-Mail (die, die ich in Monat 1 der Kaltakquise versendet habe)<\/li>\n<li>und eine erfolgreiche Kaltakquise-E-Mail (eine, die mein Gesch\u00e4ft von 200 $ auf 5.000 $ pro Monat katapultiert hat)<\/li>\n<\/ol>\n<p>Bevor wir uns mit den Details befassen, besteht eine Kaltakquise-E-Mail aus f\u00fcnf Teilen:<\/p>\n<ol>\n<li>Abonname<\/li>\n<li>Betreffzeile<\/li>\n<li>Aufh\u00e4nger<\/li>\n<li>Anpreisung<\/li>\n<li>Fragen<\/li>\n<\/ol>\n<p>Alle Teile m\u00fcssen zusammenwirken, um eine glorreiche Kaltakquise zu erm\u00f6glichen. Keine Sorge &#8211; ich zeige Ihnen jeden Teil und seine Aufgabe.<\/p>\n<p>Beginnen wir mit der schrecklichen Kaltakquise.<\/p>\n<h2>Meine furchtbare Kaltakquise-E-Mail<\/h2>\n<p>Hier ist die gesamte Kaltakquise-E-Mail in ihrer ganzen grauenhaften Pracht:<\/p>\n<img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-11954\" src=\"https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/02\/1-300x202.png\" alt=\"schlechtes kaltes E-Mail Beispiel Laura Lopuch\" width=\"580\" height=\"390\" srcset=\"https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/02\/1-300x202.png 300w, https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/02\/1-768x518.png 768w, https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/02\/1.png 880w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/>\n<h3>Schlechte Kaltakquise-E-Mail: Absendername<\/h3>\n<p>Der Absendername ist der Name des Absenders der E-Mail.<\/p>\n<p>In dieser schlechten Kaltakquise-E-Mail ist der Absendername L.V. Lopuch:<\/p>\n<img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-11958\" src=\"https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/2-and-5-300x66.png\" alt=\"schlechter Absendername\" width=\"404\" height=\"89\" srcset=\"https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/2-and-5-300x66.png 300w, https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/2-and-5.png 451w\" sizes=\"(max-width: 404px) 100vw, 404px\" \/>\n<p>Der Absendername ist von entscheidender Bedeutung.<\/p>\n<p>Aufgrund des Aufbaus des Posteingangs ist der Absendername das erste, was der Leser der E-Mail sieht. Eine Untersuchung von Super Office hat ergeben, dass 45 % der Abonnenten Ihre E-Mail aufgrund des Absendernamens lesen werden.<\/p>\n<p>Sehen Sie sich an, wie die Gmail-App den Absendernamen anzeigt:<\/p>\n<img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-11962\" src=\"https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/3-142x300.jpg\" alt=\"from name in gmail\" width=\"249\" height=\"526\" srcset=\"https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/3-142x300.jpg 142w, https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/3-485x1024.jpg 485w, https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/3-768x1621.jpg 768w, https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/3-728x1536.jpg 728w, https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/3-970x2048.jpg 970w, https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/3.jpg 1080w\" sizes=\"(max-width: 249px) 100vw, 249px\" \/>\n<p>Auch im Desktop-Gmail ist der Absendername das erste Element:<\/p>\n<img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-11966\" src=\"https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/4-300x197.png\" alt=\"from name in desktop gmail\" width=\"695\" height=\"456\" srcset=\"https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/4-300x197.png 300w, https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/4-768x505.png 768w, https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/4.png 898w\" sizes=\"(max-width: 695px) 100vw, 695px\" \/>\n<p>Daher ist ein echter, menschlich klingender Absendername der erste Test, den Ihre Kaltakquise-E-Mail bestehen muss. Ihr Absendername muss sofort Vertrauen schaffen.<\/p>\n<p>Ich bin nicht J.K. Rowling, also kann ich nicht einfach Initialen in meinem Absendernamen verwenden.<\/p>\n<h3>Schlechte Kaltakquise: Betreffzeile<\/h3>\n<p>Mir gef\u00e4llt, wie kurz diese Betreffzeile ist. Sie sticht im Posteingang hervor.<\/p>\n<img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-11958\" src=\"https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/2-and-5-300x66.png\" alt=\"schlechter Absendername\" width=\"427\" height=\"94\" srcset=\"https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/2-and-5-300x66.png 300w, https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/2-and-5.png 451w\" sizes=\"(max-width: 427px) 100vw, 427px\" \/>\n<p>Die wichtigste Aufgabe einer Betreffzeile ist jedoch:<\/p>\n<p>Sie soll daf\u00fcr sorgen, dass Ihre Kaltakquise-E-Mail ge\u00f6ffnet wird.<\/p>\n<p>Ich wei\u00df nicht, ob diese E-Mail ge\u00f6ffnet wurde.<\/p>\n<p>Denn ich habe einen schwerwiegenden Fehler begangen, bevor ich bei dieser E-Mail auf &#8220;Senden&#8221; geklickt habe: Ich habe vergessen, eine Tracking-Software zu installieren, um zu sehen, ob diese E-Mail ge\u00f6ffnet wurde.<\/p>\n<p>Ohne diesen Einblick habe ich keine Ahnung, ob diese Betreffzeile ihren Zweck erf\u00fcllt hat&#8230; oder nicht. Daher wei\u00df ich auch nicht, ob ich diese Betreffzeile bearbeiten oder beibehalten muss.<\/p>\n<p>In der Annahme, dass diese Betreffzeile nicht funktioniert hat, w\u00fcrde ich diese neuen Betreffzeilen ausprobieren:<\/p>\n<ul>\n<li>Gl\u00fcckwunsch zu Ihrem Forbes-Feature!<\/li>\n<li>Ihre neue Ver\u00f6ffentlichung \/ Disclosure Manager<\/li>\n<li>Forbes \/ Ihre k\u00fcrzliche Markteinf\u00fchrung<\/li>\n<\/ul>\n<h3>Horrorible Cold Email: Der Aufh\u00e4nger<\/h3>\n<p>Die ersten 1-3 S\u00e4tze in einer E-Mail werden als Aufh\u00e4nger bezeichnet. Stellen Sie sich vor, dass diese S\u00e4tze die Aufmerksamkeit des Lesers erregen und seinen Blick wie einen Angelhaken in der Backe festhalten.<\/p>\n<p>Hier ist der Aufh\u00e4nger in dieser schlechten Erk\u00e4ltungs-E-Mail:<\/p>\n<img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-11970\" src=\"https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/6-300x70.png\" alt=\"schlechter Aufh\u00e4nger f\u00fcr Kaltakquise\" width=\"617\" height=\"144\" srcset=\"https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/6-300x70.png 300w, https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/6-768x179.png 768w, https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/6.png 878w\" sizes=\"(max-width: 617px) 100vw, 617px\" \/>\n<p>Dieser m\u00fcde Aufh\u00e4nger versucht halbherzig, die Aufmerksamkeit des Lesers auf eine &#8220;Hey, vielleicht interessiert dich das ja&#8221;-Art zu erregen.<\/p>\n<p>Wenn ich ein Kompliment als Aufh\u00e4nger verwendet h\u00e4tte, w\u00e4re meine E-Mail st\u00e4rker gewesen, etwa so:<\/p>\n<p>&#8220;Herzlichen Gl\u00fcckwunsch zu Ihrem j\u00fcngsten Artikel in Forbes! Ich finde es toll, was [Unternehmen] tut [spezielles Kompliment, z. B.: Unternehmern helfen, mehr Steuerverg\u00fcnstigungen ohne Hilfe eines Buchhalters zu finden]&#8221;.<\/p>\n<h3>Schreckliche Kaltakquise: Anpreisung<\/h3>\n<p>Der dritte Abschnitt einer Kaltakquise-E-Mail ist die Ansprache.<\/p>\n<p>Wenn Sie an &#8220;Kaltakquise&#8221; denken, denken Sie vermutlich an den Pitch. Ja, das ist der verkaufende Teil Ihrer Kaltakquise-E-Mail.<\/p>\n<p><a href=\"https:\/\/www.lauralopuch.com\/woodpecker\"><span style=\"font-weight: 400;\">Wenn Sie mein erfolgreiches Verkaufsargument wollen, finden Sie es in dieser Vorlage. <\/span><\/a><\/p>\n<img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-11973\" src=\"https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/7-300x70.png\" alt=\"schlechte Werbebotschaft\" width=\"626\" height=\"146\" srcset=\"https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/7-300x70.png 300w, https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/7-768x179.png 768w, https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/7.png 878w\" sizes=\"(max-width: 626px) 100vw, 626px\" \/>\n<p>Die Gr\u00fcnde f\u00fcr das Scheitern dieses Pitches lassen sich in einem Wort zusammenfassen: irrelevant.<\/p>\n<p>Ich beantworte nicht die Frage, die sich der Leser meiner Werbe-E-Mails stellt: &#8220;Was ist f\u00fcr mich drin?&#8221; Stattdessen plappere ich immer nur \u00fcber mich. Ich habe sogar jeden Satz mit &#8220;ich&#8221; begonnen.<\/p>\n<p>Ich habe den Kardinalfehler der Kaltakquise-E-Mails begangen: Sprich nicht \u00fcber mich. Sprechen Sie \u00fcber das Problem des Lesers meiner E-Mail.<\/p>\n<p>Corbett Barr, Moderator der Fizzle Show, sagte k\u00fcrzlich:<\/p>\n<p>&#8220;99 % der E-Mails l\u00f6sche ich, ich mache mir nicht einmal die M\u00fche, sie zu lesen. Die einzige E-Mail, die meine Aufmerksamkeit erregt hat, war die, in der jemand sagte: &#8216;Hey, ich glaube, wir k\u00f6nnen <a href=\"https:\/\/woodpecker.co\/blog\/deliverability-checks\/\">Ihre Zustellbarkeit<\/a> um diese und jene Werte verbessern. Ich m\u00f6chte Ihnen zeigen, wie wir sie verbessern k\u00f6nnen.&#8217; Sie haben ein Video gemacht, speziell f\u00fcr uns.<\/p>\n<p>Nat\u00fcrlich schaue ich mir das an, es hat einen Wert f\u00fcr mich, ob ich diese Person nun einstelle oder nicht. Es ist ein Teil dessen, wof\u00fcr ich bezahlen w\u00fcrde. Nat\u00fcrlich werde ich es mir ansehen. Es ist einer der wenigen, die meine Aufmerksamkeit erregt haben.<\/p>\n<p>Nicht nur zeigen und nicht erz\u00e4hlen [in Ihrer Kaltakquise-E-Mail]. Zeigen Sie es auf eine Art und Weise, bei der das Unternehmen oder das Logo der Person im Vordergrund steht, so dass die Person nicht anders kann, als zu klicken, um zu sehen, was Sie f\u00fcr sie gemacht haben.<\/p>\n<p>Meine Leser der Kaltakquise-E-Mails interessierten sich nicht daf\u00fcr, weil ich sie nicht dazu brachte, sich daf\u00fcr zu interessieren, indem ich ihnen einen Mehrwert bot. Stattdessen klickten sie auf &#8220;L\u00f6schen&#8221;.<\/p>\n<h3>Schlechte Kalt-E-Mail: Fragen<\/h3>\n<p>Die Handlungsaufforderung ist der Punkt, an dem Sie den Leser Ihrer E-Mail auffordern, aktiv zu werden. Etwas zu tun. Genauer gesagt, die Aktion, die Sie von ihm erwarten&#8230; und nicht die Aktion, auf L\u00f6schen zu klicken.<\/p>\n<p>Das ist sicherlich der Grund, warum diese E-Mail aus zwei wichtigen Gr\u00fcnden gel\u00f6scht wurde:<\/p>\n<ol>\n<li>Verwendung des Wortes &#8220;sollte&#8221;<\/li>\n<li>Mangel an Klarheit \u00fcber die n\u00e4chsten Schritte<\/li>\n<\/ol>\n<h4>1. Die Verwendung des Wortes &#8220;sollte&#8221;<\/h4>\n<p>Ack, es gibt keine gute Art, dies h\u00f6flich zu formulieren. Die Verwendung des Wortes &#8220;sollte&#8221; weckt schreckliche Assoziationen an die gemeine kleine Stimme in Ihrem Kopf.<\/p>\n<p>Wie Dani DiPirro schreibt, &#8220;&#8230; wenn die meisten Menschen das Wort &#8216;sollte&#8217; denken, gibt es eine reflexartige Reaktion, dagegen zu rebellieren oder sich zumindest \u00e4rgerlich dar\u00fcber zu f\u00fchlen (wenn man nicht der rebellische Typ ist). Anstatt dich zu ermutigen, etwas anderes zu tun, best\u00e4rkt das Wort &#8216;sollte&#8217; das, was du nicht tust.<\/p>\n<p>Wenn ich das Wort &#8220;sollte&#8221; in meiner Aufforderung zum Handeln verwende, f\u00e4llt meine Bitte in die Kategorie der weinerlichen, nicht zufriedenstellenden Gef\u00fchle.<\/p>\n<h4>2. fehlende Klarheit \u00fcber die n\u00e4chsten Schritte<\/h4>\n<p>Der Leser meiner E-Mail wei\u00df nicht, was passiert, nachdem er Ja gesagt hat.<\/p>\n<p>Meine Anfrage ist mit Verwirrung gespickt:<\/p>\n<ul>\n<li>Was bedeutet &#8220;ein kurzer Anruf&#8221;? Je nach Tagesform kann dieser Anruf 5, 30 oder 60 Minuten dauern.<\/li>\n<li>Wird dieser Anruf am Telefon oder \u00fcber Zoom oder Skype stattfinden?<\/li>\n<li>Wor\u00fcber genau werden wir sprechen?<\/li>\n<\/ul>\n<p>Jede dieser Fragen stellt eine H\u00fcrde dar, die den Leser einer Kaltakquise-E-Mail davon abh\u00e4lt, Ja zu sagen.<\/p>\n<h2>Wie eine erfolgreiche Kaltakquise-E-Mail aussieht<\/h2>\n<p>Diese Werbe-E-Mail habe ich nach drei Monaten endloser Tests verfeinert. Es handelt sich um eine reale E-Mail, die ich verschickt habe und auf die ich noch am selben Tag eine Antwort erhalten habe.<\/p>\n<p>Malcolm, der CEO, den ich angeschrieben habe, hat sogar Shawnee, seine Vizepr\u00e4sidentin f\u00fcr Content Marketing, gebeten, das Projekt zu \u00fcbergeben.<\/p>\n<p>Damit signalisiert er Shawnee, dass er m\u00f6chte, dass sie m\u00f6glicherweise mit mir zusammenarbeitet. Ein enormer Glaubw\u00fcrdigkeitsschub f\u00fcr mich.<\/p>\n<img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-11976\" src=\"https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/8-300x205.png\" alt=\"cold email good example\" width=\"699\" height=\"478\" srcset=\"https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/8-300x205.png 300w, https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/8-1024x701.png 1024w, https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/8-768x525.png 768w, https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/8.png 1238w\" sizes=\"(max-width: 699px) 100vw, 699px\" \/>\n<h3>Gewinnende Kalt-E-Mail: Betreffzeile<\/h3>\n<p>Ich liebe diese Betreffzeile.<\/p>\n<p>Sie ist eine der besten, die ich je geschrieben habe, und sie wird zuverl\u00e4ssig ge\u00f6ffnet, wenn ich sie (oder eine Variation) f\u00fcr eine Werbe-E-Mail verwende.<\/p>\n<img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-11979\" src=\"https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/9-and-10-300x56.png\" alt=\"Betreffzeile gutes Beispiel\" width=\"562\" height=\"105\" srcset=\"https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/9-and-10-300x56.png 300w, https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/9-and-10-768x143.png 768w, https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/9-and-10.png 970w\" sizes=\"(max-width: 562px) 100vw, 562px\" \/>\n<p>Warum diese Betreffzeile so gut funktioniert:<\/p>\n<ul>\n<li>Verbindet ein Kompliment mit einem kleinen Einblick in mein Angebot<\/li>\n<li>Sie spielt auf den Inhalt meiner E-Mail an und macht neugierig<\/li>\n<li>Hat eine ungew\u00f6hnliche Interpunktion \/ den Backslash<\/li>\n<li>Etwas l\u00e4nger als die normale Betreffzeile einer Kaltakquise-E-Mail<\/li>\n<li>Super relevant durch den Verweis auf das Kompliment<\/li>\n<li>F\u00fchlt sich pers\u00f6nlich und menschlich an und wird nicht automatisch mit Formularfeldern ausgef\u00fcllt<\/li>\n<\/ul>\n<h3>Gewinner-Kalt-E-Mail: Von Name<\/h3>\n<p>Oh hey, diese E-Mail sieht aus, als k\u00e4me sie von einer echten Person!<\/p>\n<img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-11979\" src=\"https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/9-and-10-300x56.png\" alt=\"Betreffzeile gutes Beispiel\" width=\"601\" height=\"112\" srcset=\"https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/9-and-10-300x56.png 300w, https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/9-and-10-768x143.png 768w, https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/9-and-10.png 970w\" sizes=\"(max-width: 601px) 100vw, 601px\" \/>\n<p>Mein vollst\u00e4ndiger Name &#8211; Laura Lopuch &#8211; steht im Absendernamen. Keine Initialen oder Unklarheiten dar\u00fcber, wer ich bin. Sehen Sie sich das an, es gibt sogar ein l\u00e4chelndes Bild von mir.<\/p>\n<p>All diese Elemente tragen dazu bei, dass meine E-Mail ge\u00f6ffnet wird und sofort Vertrauen schafft.<\/p>\n<h3>Gewinnende Kalt-E-Mail: Aufh\u00e4nger<\/h3>\n<p>Denken Sie daran, dass der Aufh\u00e4nger die ersten 1-3 S\u00e4tze Ihrer Werbe-E-Mail sind. Ein guter Aufh\u00e4nger erregt sofort die Aufmerksamkeit des Lesers.<\/p>\n<p>Meine Lieblingsmethode &#8211; und eine, die ich durch viel Ausprobieren gelernt habe &#8211; ist, dem Leser ein Kompliment zu machen.<\/p>\n<p>&#8220;\u00dcberzeugen Sie eine Person auf einer Bauch-Ebene, und das Gef\u00fchl wird anhalten und anhalten. Und anhaltend&#8221;, schreibt Andrew O&#8217;Connell in der Harvard Business Review. Schmeicheleien wirken auf der Ebene des Bauchgef\u00fchls, die weitaus stabiler ist als das, was der Leser Ihrer Kaltakquise-E-Mails auf der bewussten Ebene glaubt.<\/p>\n<p>Ein Kompliment als Aufh\u00e4nger f\u00fcr Ihre Kaltakquise-E-Mail ist eine erstklassige M\u00f6glichkeit, die Aufmerksamkeit des Lesers zu gewinnen. Wir Menschen sind egoistisch. Wir interessieren uns nur f\u00fcr uns selbst.<\/p>\n<p>Aber machen Sie das Kompliment auf die richtige Art und Weise: authentisch und enthusiastisch und konkret, so wie ich Malcolm ein Kompliment gemacht habe:<\/p>\n<img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-11982\" src=\"https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/11-300x79.png\" alt=\"cold email hook good example\" width=\"645\" height=\"170\" srcset=\"https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/11-300x79.png 300w, https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/11-1024x269.png 1024w, https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/11-768x202.png 768w, https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/11.png 1135w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/>\n<p>Indem ich darauf verweise, wo ich diese Informationen gelesen habe, verleihe ich meinen Informationen Glaubw\u00fcrdigkeit, ohne dass es so aussieht, als sei ich ein seltsamer Internet-Stalker.<\/p>\n<p>\u00dcbrigens geh\u00f6re ich zu den seltsamen Internet-Stalkern, weil ich vor dem Schreiben dieser E-Mail Nachforschungen \u00fcber Malcolm und WizRocket angestellt habe. Deshalb wusste ich auch von ihrer erfolgreichen Finanzierungsrunde.<\/p>\n<p>Im n\u00e4chsten Abschnitt werde ich mehr \u00fcber meine Nachforschungen berichten.<\/p>\n<h3>Gewinnende Cold Email: Pitch<\/h3>\n<p>Dieser Pitch konzentriert sich auf die Beantwortung der Frage von Malcolm: &#8220;Was ist f\u00fcr mich drin?&#8221;<\/p>\n<p>Zu der Zeit, als ich diese E-Mail verschickt habe, habe ich Fallstudien angeboten. Um festzustellen, ob Malcolm f\u00fcr meine Dienstleistungen geeignet ist, habe ich sein Unternehmen, seine Website und sein Marketingmaterial untersucht. Um eine Antwort auf meine Frage zu finden: Hat er irgendwelche Fallstudien?<\/p>\n<p>Meine Nachforschungen ergaben, dass seine Website keine enthielt. Das hei\u00dft: Er hatte ein Problem, das ich l\u00f6sen konnte.<\/p>\n<img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-11985\" src=\"https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/12-300x79.png\" alt=\"cold email pitch good example\" width=\"626\" height=\"165\" srcset=\"https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/12-300x79.png 300w, https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/12-1024x269.png 1024w, https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/12-768x202.png 768w, https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/12.png 1135w\" sizes=\"(max-width: 626px) 100vw, 626px\" \/>\n<p>Ich habe also mein Angebot &#8211; Fallstudien &#8211; als L\u00f6sung f\u00fcr ein Problem angepriesen, das er hat &#8211; keine Fallstudien. In meinem Pitch verwendete ich eine Statistik, um meinen Standpunkt zu untermauern, warum das Hinzuf\u00fcgen von Fallstudien zu seinem Marketing ein Gewinn ist, insbesondere im Hinblick auf die j\u00fcngste Finanzierungsrunde seines Unternehmens und die Notwendigkeit, schnell zu wachsen.<\/p>\n<p>&#8220;Wenn Sie Ihre Nachforschungen angestellt haben und die Persona des Kunden verstehen, k\u00f6nnen Sie ihm sagen, wie Ihr Anruf ihn dem Erreichen von X Zielen, die Sie identifiziert haben, n\u00e4her bringt. Schlie\u00dflich ist das Erreichen ihres Ziels das, was f\u00fcr sie wirklich wichtig ist&#8221;, sagt Rachel Williams, Director of Sales bei Calendly.<\/p>\n<h3>Gewinnende kalte E-Mail: Fragen<\/h3>\n<p>Als ich regelm\u00e4\u00dfig kalte E-Mails verschickte, um neue Kunden zu gewinnen, war dies meine Lieblingsfrage: &#8220;Wann haben Sie n\u00e4chste Woche Zeit f\u00fcr ein 15-min\u00fctiges Gespr\u00e4ch?&#8221;<\/p>\n<p>Sehen Sie, ich habe sie in dieser erfolgreichen Kaltakquise-E-Mail verwendet:<\/p>\n<img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-11988\" src=\"https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/13-300x30.png\" alt=\"winning cold email example\" width=\"640\" height=\"64\" srcset=\"https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/13-300x30.png 300w, https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/13-768x78.png 768w, https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/13.png 936w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\n<p>Das hat funktioniert, aber jetzt verwende ich lieber eine direktere Frage:<\/p>\n<p>&#8220;Haben Sie n\u00e4chsten Dienstag oder Donnerstag um 9 Uhr oder 13 Uhr PT Zeit f\u00fcr einen 20-min\u00fctigen Zoom-Videochat, um alles weitere zu besprechen?&#8221;<\/p>\n<p>Diese Frage kombiniert die Kraft von:<\/p>\n<ol>\n<li>Klarheit<\/li>\n<li>Durchsetzungsverm\u00f6gen<\/li>\n<\/ol>\n<p>Die Klarheit besteht darin, dass der Leser der Kaltakquise-E-Mail genau wei\u00df, was passiert, nachdem er zugesagt hat: Wir werden uns am Dienstag oder Donnerstag um 9 Uhr oder 13 Uhr f\u00fcr 20 Minuten in einem Zoom-Call treffen.<\/p>\n<p>Die Selbstsicherheit gibt ihnen ein sicheres Gef\u00fchl. Ich fordere sie nicht auf, sich f\u00fcr den n\u00e4chsten Schritt zu entscheiden, wie es bei dieser Anfrage der Fall w\u00e4re: &#8220;Sagen Sie mir Bescheid, wenn Sie sich unterhalten m\u00f6chten.&#8221;<\/p>\n<p>Vielmehr \u00fcbernehme ich die F\u00fchrung, zeige damit mein Fachwissen und gebe ihnen das Gef\u00fchl, dass sie sich in ihrer Entscheidung sicher f\u00fchlen. <a href=\"https:\/\/www.lauralopuch.com\/woodpecker\"><span style=\"font-weight: 400;\">So habe ich mit einer einzigen Kaltakquise-E-Mail unter Verwendung dieser Vorlage einen neuen Kunden im Wert von 20.000 $ gewonnen.<\/span><\/a><\/p>\n<h3>Wie Sie diese Abrisse in Ihren Kaltakquise-E-Mails anwenden k\u00f6nnen:<\/h3>\n<p>Die Lehren aus der schrecklichen Kaltakquise-E-Mail sind:<\/p>\n<ul>\n<li>Stellen Sie sicher, dass Ihr Absendername wie ein Mensch klingt<\/li>\n<li>Beantworten Sie in Ihrer Ansprache die Frage des Lesers der Kaltakquise-E-Mail: &#8220;Was ist f\u00fcr mich drin?&#8221;<\/li>\n<li>Achte auf deine Sprache in deiner Anfrage<\/li>\n<\/ul>\n<p>\u00dcbernehmen Sie diese Strategien von der erfolgreichen Kaltakquise-E-Mail:<\/p>\n<ul>\n<li>Nutzen Sie ein echtes Kompliment, um Ihren Leser zu erw\u00e4rmen<\/li>\n<li>Recherchieren Sie beim Leser und pr\u00e4sentieren Sie Ihr Angebot als L\u00f6sung f\u00fcr seine Bed\u00fcrfnisse<\/li>\n<li>\u00dcbernehmen Sie die F\u00fchrung und schlagen Sie in Ihrer Anfrage bestimmte Daten und Zeiten vor<\/li>\n<\/ul>\n<p>\n<aside class=\"cta-block cta-block--a-version js-cta-block ab-no-10-cta-block ab-no-11-cta-block\">\n  <p class=\"cta-block__heading u-heading-preset-md-600\">Senden Sie aussagekr\u00e4ftige E-Mails und steigern Sie die Anzahl der Antworten<\/p>\n  <div class=\"cta-block__form-container\">\n    <form class=\"js-cta-block-form\" action=\"\" class=\"cta-block__button-only-form js-cta-block-no-input-form\">\n      \n\n\n\n\n\n\n\n\n<button class=\"c-button js-button c-button--color-main c-button--size-small u-focus-visible-outline\">\nKostenlose Testversion starten\n<\/button>    <\/form>\n    \n    <form class=\"c-input-button-form js-cta-block-form cta-block__form\" method=\"POST\" novalidate>\n        \n  <div class=\"c-form-field js-form-field  c-input-button-form__form-field\">\n    \n    <label class=\"c-label c-form-field__label\" for=\"cta-block-form-email-278757545\">Work email<\/label>\n\n                    \n  <input class=\"c-input  js-input c-input-button-form__input\" placeholder=\"will@woodpecker.co\" name=\"email\" id=\"cta-block-form-email-278757545\" type=\"email\" \/>\n            \n    <span class=\"c-form-field__error js-error\">\n                                      Invalid email format\n        \n\n                <\/span>\n  <\/div>\n\n        <div class=\"c-input-button-form__button\">\n          \n\n\n\n\n\n\n\n\n<button class=\"cta-block__button c-button js-button c-button--color-main c-button--size-small u-focus-visible-outline\">\n                Kostenlose Testversion starten\n        \n\n<\/button>        <\/div>\n\n            <\/form>\n  <\/div>\n<\/aside><br \/>\n<aside class=\"cta-ebook-bundle js-cta-ebook-bundle ab-no-11-cta-ebook-bundle\">\n\t<div class=\"cta-ebook-bundle__container\">\n\t\t<div class=\"cta-ebook-bundle__content\">\n\t\t\t<div class=\"u-heading-preset-md-600\">\n\t\t\t\tSign up now and get our exclusive 3-ebook pack\n\t\t\t<\/div>\n\n\t\t\t<div class=\"cta-ebook-bundle__subheading u-heading-sm-400 u-text-l-400@mobile\">\n\t\t\t\t<span class=\"u-text-bg cta-ebook-bundle__accent\">Beginners Bundle<\/span> for free!\n\t\t\t<\/div>\n\n\t\t\t<img src=\"https:\/\/woodpecker.co\/blog\/app\/themes\/woodpecker-blog\/assets\/img\/cta-ebook-bundle-drawing.svg\" alt=\"\" class=\"cta-ebook-bundle__image\">\n\n\t\t\t\n    <form class=\"c-input-button-form js-cta-ebook-bundle-form\" action=\"https:\/\/woodpecker.co\/signup\/?variant=ebook-bundle\" method=\"POST\" novalidate>\n        \n  <div class=\"c-form-field js-form-field  c-input-button-form__form-field\">\n    \n    <label class=\"c-label c-form-field__label\">Work email<\/label>\n\n                    \n  <input class=\"c-input  js-input c-input-button-form__input\" placeholder=\"will@woodpecker.co\" name=\"email\" type=\"email\" \/>\n            \n    <span class=\"c-form-field__error js-error\">\n                          \t\t\t\t\tInvalid email format\n\t\t\t\t\n\n                <\/span>\n  <\/div>\n\n        <div class=\"c-input-button-form__button\">\n          \n\n\n\n\n\n\n\n\n<button class=\" c-button js-button c-button--color-main c-button--size-small u-focus-visible-outline\">\n    \t\t\t\t\tGet free TRIAL & ebook pack\n\t\t\t\t\n\n<\/button>        <\/div>\n\n            <\/form>\n\t\t<\/div>\n\t<\/div>\n<\/aside>\n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eine gute Kaltakquise-E-Mail zu schreiben ist schwieriger als es scheint. In diesem Blogbeitrag zeigen wir Ihnen Beispiele f\u00fcr gute und schlechte E-Mails aus der Praxis. Lassen Sie sich von ihnen inspirieren, wenn Sie Ihre eigenen erstellen wollen. Ich habe die Expertin f\u00fcr Kaltakquise und unsere Partnerin Laura Lopuch gebeten, sich zu diesem Thema zu \u00e4u\u00dfern [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":22539,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[91],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Beispiele f\u00fcr gute und schlechte Kaltakquise-E-Mails aus der Praxis<\/title>\n<meta name=\"description\" content=\"Eine gute Kaltakquise-E-Mail zu schreiben ist schwieriger, als es scheint. Sehen Sie sich zwei Beispiele aus dem wirklichen Leben an, um zu sehen, was gut und was schlecht ist.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/woodpecker.co\/blog\/de\/von-schrecklichen-kalt-e-mails-zu-gewinnenden-kalt-e-mails-zwei-beispiele-aus-der-praxis\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Beispiele f\u00fcr gute und schlechte Kaltakquise-E-Mails aus der Praxis\" \/>\n<meta property=\"og:description\" content=\"Eine gute Kaltakquise-E-Mail zu schreiben ist schwieriger, als es scheint. Sehen Sie sich zwei Beispiele aus dem wirklichen Leben an, um zu sehen, was gut und was schlecht ist.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/woodpecker.co\/blog\/de\/von-schrecklichen-kalt-e-mails-zu-gewinnenden-kalt-e-mails-zwei-beispiele-aus-der-praxis\/\" \/>\n<meta property=\"og:site_name\" content=\"Woodpecker Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/business.facebook.com\/woodpeckerapp\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-23T11:16:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/31.03.2020-From-Horrible-Cold-Email-to-Winning-Cold-Email-Two-Real-Life-Examples-blog-01.png\" \/>\n\t<meta property=\"og:image:width\" content=\"650\" \/>\n\t<meta property=\"og:image:height\" content=\"391\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@woodpeckerapp\" \/>\n<meta name=\"twitter:site\" content=\"@woodpeckerapp\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/woodpecker.co\/blog\/de\/von-schrecklichen-kalt-e-mails-zu-gewinnenden-kalt-e-mails-zwei-beispiele-aus-der-praxis\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/woodpecker.co\/blog\/de\/von-schrecklichen-kalt-e-mails-zu-gewinnenden-kalt-e-mails-zwei-beispiele-aus-der-praxis\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/woodpecker.co\/blog\/#\/schema\/person\/f85b7057a1d35722cc35af5bb6af5fbe\"},\"headline\":\"Von schrecklichen Kalt-E-Mails zu gewinnenden Kalt-E-Mails: Zwei Beispiele aus der Praxis\",\"datePublished\":\"2023-08-23T11:16:49+00:00\",\"dateModified\":\"2023-08-23T11:16:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/woodpecker.co\/blog\/de\/von-schrecklichen-kalt-e-mails-zu-gewinnenden-kalt-e-mails-zwei-beispiele-aus-der-praxis\/\"},\"wordCount\":2341,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/woodpecker.co\/blog\/#organization\"},\"articleSection\":[\"Cold email basics\"],\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/woodpecker.co\/blog\/de\/von-schrecklichen-kalt-e-mails-zu-gewinnenden-kalt-e-mails-zwei-beispiele-aus-der-praxis\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/woodpecker.co\/blog\/de\/von-schrecklichen-kalt-e-mails-zu-gewinnenden-kalt-e-mails-zwei-beispiele-aus-der-praxis\/\",\"url\":\"https:\/\/woodpecker.co\/blog\/de\/von-schrecklichen-kalt-e-mails-zu-gewinnenden-kalt-e-mails-zwei-beispiele-aus-der-praxis\/\",\"name\":\"Beispiele f\u00fcr gute und schlechte Kaltakquise-E-Mails aus der Praxis\",\"isPartOf\":{\"@id\":\"https:\/\/woodpecker.co\/blog\/#website\"},\"datePublished\":\"2023-08-23T11:16:49+00:00\",\"dateModified\":\"2023-08-23T11:16:49+00:00\",\"description\":\"Eine gute Kaltakquise-E-Mail zu schreiben ist schwieriger, als es scheint. Sehen Sie sich zwei Beispiele aus dem wirklichen Leben an, um zu sehen, was gut und was schlecht ist.\",\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/woodpecker.co\/blog\/de\/von-schrecklichen-kalt-e-mails-zu-gewinnenden-kalt-e-mails-zwei-beispiele-aus-der-praxis\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/woodpecker.co\/blog\/#website\",\"url\":\"https:\/\/woodpecker.co\/blog\/\",\"name\":\"Woodpecker Blog\",\"description\":\"Woodpecker Blog - Pro Tips on Cold Emails, Follow-ups, Sales &amp; Growth\",\"publisher\":{\"@id\":\"https:\/\/woodpecker.co\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/woodpecker.co\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/woodpecker.co\/blog\/#organization\",\"name\":\"Woodpecker.co\",\"url\":\"https:\/\/woodpecker.co\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/woodpecker.co\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/woodpecker.co\/blog\/app\/uploads\/2015\/06\/WP_Logo_WersjaPodstawowa_Pionowa_CzarneTlo_RGB.jpg\",\"contentUrl\":\"https:\/\/woodpecker.co\/blog\/app\/uploads\/2015\/06\/WP_Logo_WersjaPodstawowa_Pionowa_CzarneTlo_RGB.jpg\",\"width\":1240,\"height\":874,\"caption\":\"Woodpecker.co\"},\"image\":{\"@id\":\"https:\/\/woodpecker.co\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/business.facebook.com\/woodpeckerapp\",\"https:\/\/twitter.com\/woodpeckerapp\",\"https:\/\/www.instagram.com\/woodpeckerapp\/\",\"https:\/\/www.linkedin.com\/company\/woodpecker-co\/\",\"https:\/\/www.youtube.com\/channel\/UCNN9wM55yaNI-KEZCfh66_A\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/woodpecker.co\/blog\/#\/schema\/person\/f85b7057a1d35722cc35af5bb6af5fbe\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/woodpecker.co\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1af5f0dabdc3c6a0dbc94a2d57fce1bb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1af5f0dabdc3c6a0dbc94a2d57fce1bb?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/woodpecker.co\/blog\/de\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Beispiele f\u00fcr gute und schlechte Kaltakquise-E-Mails aus der Praxis","description":"Eine gute Kaltakquise-E-Mail zu schreiben ist schwieriger, als es scheint. Sehen Sie sich zwei Beispiele aus dem wirklichen Leben an, um zu sehen, was gut und was schlecht ist.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/woodpecker.co\/blog\/de\/von-schrecklichen-kalt-e-mails-zu-gewinnenden-kalt-e-mails-zwei-beispiele-aus-der-praxis\/","og_locale":"de_DE","og_type":"article","og_title":"Beispiele f\u00fcr gute und schlechte Kaltakquise-E-Mails aus der Praxis","og_description":"Eine gute Kaltakquise-E-Mail zu schreiben ist schwieriger, als es scheint. Sehen Sie sich zwei Beispiele aus dem wirklichen Leben an, um zu sehen, was gut und was schlecht ist.","og_url":"https:\/\/woodpecker.co\/blog\/de\/von-schrecklichen-kalt-e-mails-zu-gewinnenden-kalt-e-mails-zwei-beispiele-aus-der-praxis\/","og_site_name":"Woodpecker Blog","article_publisher":"https:\/\/business.facebook.com\/woodpeckerapp","article_published_time":"2023-08-23T11:16:49+00:00","og_image":[{"width":650,"height":391,"url":"https:\/\/woodpecker.co\/blog\/app\/uploads\/2021\/04\/31.03.2020-From-Horrible-Cold-Email-to-Winning-Cold-Email-Two-Real-Life-Examples-blog-01.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_creator":"@woodpeckerapp","twitter_site":"@woodpeckerapp","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/woodpecker.co\/blog\/de\/von-schrecklichen-kalt-e-mails-zu-gewinnenden-kalt-e-mails-zwei-beispiele-aus-der-praxis\/#article","isPartOf":{"@id":"https:\/\/woodpecker.co\/blog\/de\/von-schrecklichen-kalt-e-mails-zu-gewinnenden-kalt-e-mails-zwei-beispiele-aus-der-praxis\/"},"author":{"name":"admin","@id":"https:\/\/woodpecker.co\/blog\/#\/schema\/person\/f85b7057a1d35722cc35af5bb6af5fbe"},"headline":"Von schrecklichen Kalt-E-Mails zu gewinnenden Kalt-E-Mails: Zwei Beispiele aus der Praxis","datePublished":"2023-08-23T11:16:49+00:00","dateModified":"2023-08-23T11:16:49+00:00","mainEntityOfPage":{"@id":"https:\/\/woodpecker.co\/blog\/de\/von-schrecklichen-kalt-e-mails-zu-gewinnenden-kalt-e-mails-zwei-beispiele-aus-der-praxis\/"},"wordCount":2341,"commentCount":0,"publisher":{"@id":"https:\/\/woodpecker.co\/blog\/#organization"},"articleSection":["Cold email basics"],"inLanguage":"de-DE","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/woodpecker.co\/blog\/de\/von-schrecklichen-kalt-e-mails-zu-gewinnenden-kalt-e-mails-zwei-beispiele-aus-der-praxis\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/woodpecker.co\/blog\/de\/von-schrecklichen-kalt-e-mails-zu-gewinnenden-kalt-e-mails-zwei-beispiele-aus-der-praxis\/","url":"https:\/\/woodpecker.co\/blog\/de\/von-schrecklichen-kalt-e-mails-zu-gewinnenden-kalt-e-mails-zwei-beispiele-aus-der-praxis\/","name":"Beispiele f\u00fcr gute und schlechte Kaltakquise-E-Mails aus der Praxis","isPartOf":{"@id":"https:\/\/woodpecker.co\/blog\/#website"},"datePublished":"2023-08-23T11:16:49+00:00","dateModified":"2023-08-23T11:16:49+00:00","description":"Eine gute Kaltakquise-E-Mail zu schreiben ist schwieriger, als es scheint. Sehen Sie sich zwei Beispiele aus dem wirklichen Leben an, um zu sehen, was gut und was schlecht ist.","inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/woodpecker.co\/blog\/de\/von-schrecklichen-kalt-e-mails-zu-gewinnenden-kalt-e-mails-zwei-beispiele-aus-der-praxis\/"]}]},{"@type":"WebSite","@id":"https:\/\/woodpecker.co\/blog\/#website","url":"https:\/\/woodpecker.co\/blog\/","name":"Woodpecker Blog","description":"Woodpecker Blog - Pro Tips on Cold Emails, Follow-ups, Sales &amp; Growth","publisher":{"@id":"https:\/\/woodpecker.co\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/woodpecker.co\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/woodpecker.co\/blog\/#organization","name":"Woodpecker.co","url":"https:\/\/woodpecker.co\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/woodpecker.co\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/woodpecker.co\/blog\/app\/uploads\/2015\/06\/WP_Logo_WersjaPodstawowa_Pionowa_CzarneTlo_RGB.jpg","contentUrl":"https:\/\/woodpecker.co\/blog\/app\/uploads\/2015\/06\/WP_Logo_WersjaPodstawowa_Pionowa_CzarneTlo_RGB.jpg","width":1240,"height":874,"caption":"Woodpecker.co"},"image":{"@id":"https:\/\/woodpecker.co\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/business.facebook.com\/woodpeckerapp","https:\/\/twitter.com\/woodpeckerapp","https:\/\/www.instagram.com\/woodpeckerapp\/","https:\/\/www.linkedin.com\/company\/woodpecker-co\/","https:\/\/www.youtube.com\/channel\/UCNN9wM55yaNI-KEZCfh66_A"]},{"@type":"Person","@id":"https:\/\/woodpecker.co\/blog\/#\/schema\/person\/f85b7057a1d35722cc35af5bb6af5fbe","name":"admin","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/woodpecker.co\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1af5f0dabdc3c6a0dbc94a2d57fce1bb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1af5f0dabdc3c6a0dbc94a2d57fce1bb?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/woodpecker.co\/blog\/de\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/woodpecker.co\/blog\/de\/wp-json\/wp\/v2\/posts\/22526"}],"collection":[{"href":"https:\/\/woodpecker.co\/blog\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/woodpecker.co\/blog\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/woodpecker.co\/blog\/de\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/woodpecker.co\/blog\/de\/wp-json\/wp\/v2\/comments?post=22526"}],"version-history":[{"count":1,"href":"https:\/\/woodpecker.co\/blog\/de\/wp-json\/wp\/v2\/posts\/22526\/revisions"}],"predecessor-version":[{"id":22527,"href":"https:\/\/woodpecker.co\/blog\/de\/wp-json\/wp\/v2\/posts\/22526\/revisions\/22527"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/woodpecker.co\/blog\/de\/wp-json\/wp\/v2\/media\/22539"}],"wp:attachment":[{"href":"https:\/\/woodpecker.co\/blog\/de\/wp-json\/wp\/v2\/media?parent=22526"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/woodpecker.co\/blog\/de\/wp-json\/wp\/v2\/categories?post=22526"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/woodpecker.co\/blog\/de\/wp-json\/wp\/v2\/tags?post=22526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}